{"id":14596,"date":"2019-03-22T00:00:00","date_gmt":"2019-03-21T23:00:00","guid":{"rendered":"https:\/\/obcocinas.es\/ob-cozinhas-esto-presente-sadecc-2019-paris-frana\/"},"modified":"2025-12-03T09:22:05","modified_gmt":"2025-12-03T08:22:05","slug":"ob-cozinhas-esto-presente-sadecc-2019-paris-frana","status":"publish","type":"post","link":"https:\/\/obcocinas.es\/pt\/blog\/ob-cozinhas-esto-presente-sadecc-2019-paris-frana\/","title":{"rendered":"A OB kitchens estar\u00e1 presente na SADECC 2019 em Paris (Fran\u00e7a)"},"content":{"rendered":"<div>OB Kitchens estar\u00e1 presente na nova edi\u00e7\u00e3o da feira de cozinhas e equipamentos (SADECC) que se realizar\u00e1 em Paris de 5 a 8 de abril.Mais uma vez, a OB Kitchens estar\u00e1 presente neste sal\u00e3o onde apresentar\u00e1 ao mercado franc\u00eas o projeto PR-19, bem como o dossier de novidades para este ano.Convidamo-lo a assistir \u00e0 nossa exposi\u00e7\u00e3o localizada no HALL 7.1 Stand 20B para que possamos apresentar-lhe pessoalmente todas as nossas propostas para 2019.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>OB Kitchens estar\u00e1 presente na nova edi\u00e7\u00e3o da feira de cozinhas e equipamentos (SADECC) que se realizar\u00e1 em Paris de 5 a 8 de abril.Mais uma vez, a OB Kitchens estar\u00e1 presente neste sal\u00e3o onde apresentar\u00e1 ao mercado franc\u00eas o projeto PR-19, bem como o dossier de novidades para este ano.Convidamo-lo a assistir \u00e0 nossa [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14597,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1336],"tags":[],"class_list":["post-14596","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-corporativo"],"_links":{"self":[{"href":"https:\/\/obcocinas.es\/pt\/wp-json\/wp\/v2\/posts\/14596","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/obcocinas.es\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/obcocinas.es\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/obcocinas.es\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/obcocinas.es\/pt\/wp-json\/wp\/v2\/comments?post=14596"}],"version-history":[{"count":1,"href":"https:\/\/obcocinas.es\/pt\/wp-json\/wp\/v2\/posts\/14596\/revisions"}],"predecessor-version":[{"id":15202,"href":"https:\/\/obcocinas.es\/pt\/wp-json\/wp\/v2\/posts\/14596\/revisions\/15202"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/obcocinas.es\/pt\/wp-json\/wp\/v2\/media\/14597"}],"wp:attachment":[{"href":"https:\/\/obcocinas.es\/pt\/wp-json\/wp\/v2\/media?parent=14596"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/obcocinas.es\/pt\/wp-json\/wp\/v2\/categories?post=14596"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/obcocinas.es\/pt\/wp-json\/wp\/v2\/tags?post=14596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}