{"id":14586,"date":"2022-02-22T00:00:00","date_gmt":"2022-02-21T23:00:00","guid":{"rendered":"https:\/\/obcocinas.es\/as-nossas-cozinhas-kobe\/"},"modified":"2026-02-26T19:43:08","modified_gmt":"2026-02-26T18:43:08","slug":"as-nossas-cozinhas-kobe","status":"publish","type":"post","link":"https:\/\/obcocinas.es\/pt\/blog\/as-nossas-cozinhas-kobe\/","title":{"rendered":"As nossas cozinhas: Kobe"},"content":{"rendered":"<div>\n<p>Se procura uma cozinha de linhas simples e <strong>elegantes sem sacrificar a funcionalidade<\/strong>, Kobe \u00e9 a sua melhor op\u00e7\u00e3o.<\/p>\n<p>A Kobe faz parte do conceito PR-19, desenvolvido pela OB Cocinas. O principal objetivo do PR-19 \u00e9 <strong>aliar a est\u00e9tica \u00e0 funcionalidade <\/strong>, satisfazendo as mais elevadas exig\u00eancias do mercado e, claro, com a m\u00e1xima qualidade.<\/p>\n<h2>Concebido para a sua casa<\/h2>\n<p>Calor e tranquilidade. \u00c9 essa a sensa\u00e7\u00e3o que o Kobe transmite. N\u00e3o s\u00f3 pelo tom da sua madeira; o seu acabamento de gr\u00e3o horizontal, a simplicidade do seu desenho, sem relevos nem puxadores, conseguem um efeito de <strong>serenidade e discri\u00e7\u00e3o<\/strong> na sua cozinha.\u00a0<\/p>\n<p>A sua simplicidade torna-o muito vers\u00e1til e, por isso, perfeitamente adapt\u00e1vel a todas as necessidades e a qualquer tipo de estilo e decora\u00e7\u00e3o. Pode combinar o seu PR-19 Kobe adicionando outros elementos funcionais ou decorativos em tons mais escuros. Como se pode ver nas imagens, materiais como o vidro, o metal e a pedra combinam na perfei\u00e7\u00e3o.<\/p>\n<h2>Conforto e eleg\u00e2ncia<\/h2>\n<p>Na PR-19 Kobe, como em todas as cozinhas OB, o conforto \u00e9 uma prioridade, algo essencial no dia a dia de uma casa e a chave para desfrutar plenamente dos momentos na cozinha.<\/p>\n<p>O seu <strong>sistema de abertura<\/strong> facilita o trabalho na cozinha. Al\u00e9m disso, gra\u00e7as ao seu puxador integrado na parte frontal, n\u00e3o s\u00f3 simplifica o gesto, como tamb\u00e9m reduz o impacto visual do m\u00f3vel, o que o torna muito vers\u00e1til e adapt\u00e1vel a qualquer tipo de decora\u00e7\u00e3o ou ambiente.<\/p>\n<p>E por falar em mobili\u00e1rio, as <strong>gavetas Elegance<\/strong> completam esta combina\u00e7\u00e3o, conferindo distin\u00e7\u00e3o sem sacrificar o m\u00e1ximo conforto gra\u00e7as \u00e0s suas corredi\u00e7as sincronizadas de extens\u00e3o total com amortecimento integrado. Mas n\u00e3o se deixe enganar por esta aparente simplicidade, as gavetas Elegance t\u00eam uma <strong>capacidade de carga at\u00e9 40 kg<\/strong> por corredi\u00e7a. Se est\u00e1 preocupado com a forma de as combinar, tem uma infinidade de possibilidades para os interiores de cada m\u00f3dulo e pode escolher entre os acabamentos Orion Grey e Inox.<\/p>\n<\/div>\n<div>\n<div>\u00a0<\/div>\n<\/div>\n\n\n<figure class=\"wp-block-image size-full ob-post-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1365\" height=\"2048\" sizes=\"auto, (max-width: 1365px) 100vw, 1365px\" src=\"https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/220223_01.-pim2-2000_q.jpg\" alt=\"Caj\u00f3n extra\u00edble de cocina con botellas y tarros organizados junto al horno.\" class=\"wp-image-3699\" srcset=\"https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/220223_01.-pim2-2000_q-jpg.avif 1365w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/220223_01.-pim2-2000_q-200x300-jpg.avif 200w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/220223_01.-pim2-2000_q-683x1024-jpg.avif 683w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/220223_01.-pim2-2000_q-1024x1536-jpg.avif 1024w\" \/><\/figure>\n\n\n<\/div>\n<div>\n<h2>Detalhes \u00fanicos<\/h2>\n<\/div>\n<\/div>\n<div>\n<p>Uma cozinha Kobe PR-19 <strong>\u00e9 uma cozinha \u00fanica<\/strong>. E s\u00e3o os pormenores que fazem a diferen\u00e7a. Aos m\u00f3dulos b\u00e1sicos podem juntar-se outros elementos que iluminam e criam a harmonia perfeita. \u00c9 o caso da <strong>vitrina Bold<\/strong> que, juntamente com o m\u00f3dulo decorativo com ilumina\u00e7\u00e3o interior e exterior, dar\u00e1 \u00e0 sua cozinha aquele toque especial.<\/p>\n<p>E para manter tudo arrumado e \u00e0 m\u00e3o, e continuar a acrescentar ao conjunto est\u00e9tico, tem a <strong>Prateleira Q20<\/strong>, que lhe permite organizar, separar e colocar utens\u00edlios de todo o tipo para continuar a facilitar a sua vida.<\/p>\n<\/div>\n<div>\n<div>\n\n\n<figure class=\"wp-block-image size-full ob-post-image\"><img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1125\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\" src=\"https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/220223_02.-pim2-2000_q.jpg\" alt=\"220223_02.-pim2-2000_q\" class=\"wp-image-3700\" srcset=\"https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/220223_02.-pim2-2000_q-jpg.avif 2000w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/220223_02.-pim2-2000_q-1024x576.jpg 1024w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/220223_02.-pim2-2000_q-1536x864.jpg 1536w\" \/><\/figure>\n\n\n<\/div>\n<div>\n<h2>Crie o seu momento<\/h2>\n<\/div>\n<\/div>\n<div>\n<p>Na OB Cocinas sabemos que a cozinha \u00e9 o cora\u00e7\u00e3o de uma casa. E adoramos criar espa\u00e7os para desfrutar em fam\u00edlia, com amigos e, porque n\u00e3o, at\u00e9 mesmo sozinho. \u00c9 o caso deste <strong>bar<\/strong>, uma zona ideal para pequenos-almo\u00e7os, lanches e para se reunir enquanto se cozinha. Alguns bancos altos \u00e0 volta e <em>voil\u00e0,<\/em> um novo canto preferido.<\/p>\n<\/div>\n<div>\n\n\n<figure class=\"wp-block-image size-full ob-post-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1365\" height=\"2048\" sizes=\"auto, (max-width: 1365px) 100vw, 1365px\" src=\"https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/220223_03.-pim2-2000_q.jpg\" alt=\"220223_03.-pim2-2000_q\" class=\"wp-image-3701\" srcset=\"https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/220223_03.-pim2-2000_q-jpg.avif 1365w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/220223_03.-pim2-2000_q-200x300.jpg 200w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/220223_03.-pim2-2000_q-683x1024.jpg 683w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/220223_03.-pim2-2000_q-1024x1536-jpg.avif 1024w\" \/><\/figure>\n\n\n<div>\n<p>deseja mais informa\u00e7\u00f5es sobre a nossa cozinha Kobe? <strong>Descarregue aqui a brochura<\/strong> para conhecer todos os pormenores. Se ainda n\u00e3o se decidiu e quer ver o resto das linhas da OB Cocinas, <strong>descarregue o cat\u00e1logo completo<\/strong>. Encontrar\u00e1 todos os estilos, aplica\u00e7\u00f5es e funcionalidades que possa imaginar para iniciar o seu projeto e criar connosco mais vida na cozinha.<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Se procura uma cozinha de linhas simples e elegantes sem sacrificar a funcionalidade, Kobe \u00e9 a sua melhor op\u00e7\u00e3o. A Kobe faz parte do conceito PR-19, desenvolvido pela OB Cocinas. O principal objetivo do PR-19 \u00e9 aliar a est\u00e9tica \u00e0 funcionalidade , satisfazendo as mais elevadas exig\u00eancias do mercado e, claro, com a m\u00e1xima qualidade. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14587,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1335],"tags":[],"class_list":["post-14586","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nuestras-cocinas"],"_links":{"self":[{"href":"https:\/\/obcocinas.es\/pt\/wp-json\/wp\/v2\/posts\/14586","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/obcocinas.es\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/obcocinas.es\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/obcocinas.es\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/obcocinas.es\/pt\/wp-json\/wp\/v2\/comments?post=14586"}],"version-history":[{"count":2,"href":"https:\/\/obcocinas.es\/pt\/wp-json\/wp\/v2\/posts\/14586\/revisions"}],"predecessor-version":[{"id":18892,"href":"https:\/\/obcocinas.es\/pt\/wp-json\/wp\/v2\/posts\/14586\/revisions\/18892"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/obcocinas.es\/pt\/wp-json\/wp\/v2\/media\/14587"}],"wp:attachment":[{"href":"https:\/\/obcocinas.es\/pt\/wp-json\/wp\/v2\/media?parent=14586"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/obcocinas.es\/pt\/wp-json\/wp\/v2\/categories?post=14586"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/obcocinas.es\/pt\/wp-json\/wp\/v2\/tags?post=14586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}