{"id":14381,"date":"2024-09-08T00:00:00","date_gmt":"2024-09-07T22:00:00","guid":{"rendered":"https:\/\/obcocinas.es\/como-dar-a-sua-cozinha-um-retoque-luxuoso\/"},"modified":"2025-12-03T09:15:50","modified_gmt":"2025-12-03T08:15:50","slug":"como-dar-a-sua-cozinha-um-retoque-luxuoso","status":"publish","type":"post","link":"https:\/\/obcocinas.es\/pt\/blog\/como-dar-a-sua-cozinha-um-retoque-luxuoso\/","title":{"rendered":"Como dar um toque de luxo \u00e0 sua cozinha"},"content":{"rendered":"<div>\n<p>H\u00e1 muito que as cozinhas deixaram de ser um mero local de trabalho, com a est\u00e9tica subordinada \u00e0 funcionalidade e longe dos olhares dos visitantes que chegam a casa.\u00a0<\/p>\n<p>Atualmente, \u00e9 um espa\u00e7o onde queremos n\u00e3o s\u00f3 viver e sentirmo-nos bem, mas tamb\u00e9m exibi-lo com orgulho e integr\u00e1-lo na nossa casa.<\/p>\n<p>Talvez seja por isso que cada vez mais pessoas querem dar um toque de luxo \u00e0s suas cozinhas. Luxo, claro, interpretado como sofistica\u00e7\u00e3o, paix\u00e3o, diferencia\u00e7\u00e3o e conforto.<\/p>\n<p>Se \u00e9 uma dessas pessoas, hoje vamos contar-lhe alguns truques para viver a sua cozinha com todos os pormenores de luxo. Tome nota!<\/p>\n<h2>Ouro intemporal\u00a0 \u00a0<\/h2>\n<p>Comecemos por um dos elementos b\u00e1sicos do luxo por excel\u00eancia: os tons dourados. Este acabamento passou por um renascimento nos \u00faltimos anos, sempre incorporado de forma subtil na decora\u00e7\u00e3o da sua casa.<\/p>\n<p>No caso das cozinhas, \u00e9 frequentemente integrado em designs simples e at\u00e9 minimalistas atrav\u00e9s de puxadores, torneiras&#8230; e at\u00e9 lava-loi\u00e7as!<\/p>\n<p>Tamb\u00e9m atrav\u00e9s de detalhes em m\u00f3veis ou utens\u00edlios de cozinha, como neste projeto do nosso distribuidor franc\u00eas ABP Partner e da decoradora Alexandra Roman. O resultado faz-nos lembrar os caf\u00e9s e bistr\u00f4s de Paris. Muito chique!<\/p>\n<\/div>\n<div>\n<div>\u00a0<\/div>\n<\/div>\n\n\n<figure class=\"wp-block-image size-full ob-post-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1534\" height=\"2048\" sizes=\"auto, (max-width: 1534px) 100vw, 1534px\" src=\"https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/abp_partner_-_cocina_verde_con_el_respresentante_nfsagent_y_la_decoradora_alexandra_roman_5.-pim2-2000_q.jpeg\" alt=\"abp_partner_-_cocina_verde_con_el_respresentante_nfsagent_y_la_decoradora_alexandra_roman_5.-pim2-2000_q\" class=\"wp-image-3254\" srcset=\"https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/abp_partner_-_cocina_verde_con_el_respresentante_nfsagent_y_la_decoradora_alexandra_roman_5.-pim2-2000_q-jpeg.avif 1534w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/abp_partner_-_cocina_verde_con_el_respresentante_nfsagent_y_la_decoradora_alexandra_roman_5.-pim2-2000_q-225x300.jpeg 225w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/abp_partner_-_cocina_verde_con_el_respresentante_nfsagent_y_la_decoradora_alexandra_roman_5.-pim2-2000_q-767x1024-jpeg.avif 767w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/abp_partner_-_cocina_verde_con_el_respresentante_nfsagent_y_la_decoradora_alexandra_roman_5.-pim2-2000_q-1151x1536-jpeg.avif 1151w\" \/><\/figure>\n\n\n<\/div>\n<div>\n<p>ABP Partner + Alexandra Roman<\/p>\n<\/div>\n<\/div>\n<div>\n<h2>N\u00e3o pare de brilhar<\/h2>\n<p>Seguindo a linha dos cl\u00e1ssicos de luxo, aqui est\u00e1 outra ideia: incluir o vidro no design da sua cozinha, especialmente se optar por cores neutras.<\/p>\n<p>Neste exemplo da Cuisine ETC, encontramos uma bela combina\u00e7\u00e3o: a do nosso modelo laminado liberia em tons de cinzento com puxadores de diamante. A neutralidade das frentes fica muito bem com o toque opulento dos puxadores.<\/p>\n<\/div>\n<div>\n<div>\n<div>\n<div>\n\n\n<figure class=\"wp-block-image size-full ob-post-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1112\" height=\"2048\" sizes=\"auto, (max-width: 1112px) 100vw, 1112px\" src=\"https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/cuisine-etc---cocina-grisacea-con-encimera-negra-y-tiradores-transparentes-_1.-pim2-2000_q.jpg\" alt=\"cuisine-etc---cocina-grisacea-con-encimera-negra-y-tiradores-transparentes-_1.-pim2-2000_q\" class=\"wp-image-3255\" srcset=\"https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/cuisine-etc---cocina-grisacea-con-encimera-negra-y-tiradores-transparentes-_1.-pim2-2000_q-jpg.avif 1112w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/cuisine-etc---cocina-grisacea-con-encimera-negra-y-tiradores-transparentes-_1.-pim2-2000_q-163x300-jpg.avif 163w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/cuisine-etc---cocina-grisacea-con-encimera-negra-y-tiradores-transparentes-_1.-pim2-2000_q-556x1024-jpg.avif 556w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/cuisine-etc---cocina-grisacea-con-encimera-negra-y-tiradores-transparentes-_1.-pim2-2000_q-834x1536-jpg.avif 834w\" \/><\/figure>\n\n\n<\/div>\n<div>\n\n\n<figure class=\"wp-block-image size-full ob-post-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1035\" height=\"2048\" sizes=\"auto, (max-width: 1035px) 100vw, 1035px\" src=\"https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/cuisine-etc---cocina-grisacea-con-encimera-negra-y-tiradores-transparentes-_3.-pim2-2000_q.jpg\" alt=\"cuisine-etc---cocina-grisacea-con-encimera-negra-y-tiradores-transparentes-_3.-pim2-2000_q\" class=\"wp-image-3256\" srcset=\"https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/cuisine-etc---cocina-grisacea-con-encimera-negra-y-tiradores-transparentes-_3.-pim2-2000_q-jpg.avif 1035w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/cuisine-etc---cocina-grisacea-con-encimera-negra-y-tiradores-transparentes-_3.-pim2-2000_q-152x300-jpg.avif 152w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/cuisine-etc---cocina-grisacea-con-encimera-negra-y-tiradores-transparentes-_3.-pim2-2000_q-518x1024-jpg.avif 518w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/cuisine-etc---cocina-grisacea-con-encimera-negra-y-tiradores-transparentes-_3.-pim2-2000_q-776x1536-jpg.avif 776w\" \/><\/figure>\n\n\n<\/div>\n<\/div>\n<\/div>\n<div>\n<p>Cuisine ETC<\/p>\n<\/div>\n<\/div>\n<div>\n<h2>Minimalismo de luxo<\/h2>\n<p>Quando se trata de luxo, os materiais s\u00e3o tudo, especialmente se optarmos por um ambiente minimalista.<\/p>\n<p>\u00c9 o que o Sistema Cuina faz em quase todos os seus projectos de cozinha, nos quais opta n\u00e3o s\u00f3 pelos nossos m\u00f3veis, mas tamb\u00e9m por outros materiais, como o tampo de gr\u00e9s porcel\u00e2nico com efeito de pedra da foto abaixo.<\/p>\n<\/div>\n<div>\n<div>\n\n\n<figure class=\"wp-block-image size-full ob-post-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1697\" height=\"2048\" sizes=\"auto, (max-width: 1697px) 100vw, 1697px\" src=\"https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/canovas-sistema-cuina-barcelona---cocina-negra-encimera-cemento-con-peninsula-abierta-al-salon-_5_-_1.-pim2-2000_q.jpg\" alt=\"canovas-sistema-cuina-barcelona---cocina-negra-encimera-cemento-con-peninsula-abierta-al-salon-_5_-_1.-pim2-2000_q\" class=\"wp-image-3257\" srcset=\"https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/canovas-sistema-cuina-barcelona---cocina-negra-encimera-cemento-con-peninsula-abierta-al-salon-_5_-_1.-pim2-2000_q-jpg.avif 1697w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/canovas-sistema-cuina-barcelona---cocina-negra-encimera-cemento-con-peninsula-abierta-al-salon-_5_-_1.-pim2-2000_q-249x300-jpg.avif 249w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/canovas-sistema-cuina-barcelona---cocina-negra-encimera-cemento-con-peninsula-abierta-al-salon-_5_-_1.-pim2-2000_q-849x1024.jpg 849w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/canovas-sistema-cuina-barcelona---cocina-negra-encimera-cemento-con-peninsula-abierta-al-salon-_5_-_1.-pim2-2000_q-1273x1536.jpg 1273w\" \/><\/figure>\n\n\n<\/div>\n<div>\n<p>Sistema Cuina<\/p>\n<\/div>\n<\/div>\n<div>\n<p>Este projeto d\u00e1-nos outra chave para um design de luxo minimalista: integrar o maior n\u00famero poss\u00edvel de electrodom\u00e9sticos e, se n\u00e3o for poss\u00edvel, escolh\u00ea-los na mesma cor que as frentes da cozinha.<\/p>\n<\/div>\n<div>\n<div>\n\n\n<figure class=\"wp-block-image size-full ob-post-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1536\" height=\"2048\" sizes=\"auto, (max-width: 1536px) 100vw, 1536px\" src=\"https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/canovas-sistema-cuina-barcelona---cocina-negra-encimera-cemento-con-peninsula-abierta-al-salon-_6.-pim2-2000_q.jpg\" alt=\"canovas-sistema-cuina-barcelona---cocina-negra-encimera-cemento-con-peninsula-abierta-al-salon-_6.-pim2-2000_q\" class=\"wp-image-3258\" srcset=\"https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/canovas-sistema-cuina-barcelona---cocina-negra-encimera-cemento-con-peninsula-abierta-al-salon-_6.-pim2-2000_q-jpg.avif 1536w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/canovas-sistema-cuina-barcelona---cocina-negra-encimera-cemento-con-peninsula-abierta-al-salon-_6.-pim2-2000_q-225x300-jpg.avif 225w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/canovas-sistema-cuina-barcelona---cocina-negra-encimera-cemento-con-peninsula-abierta-al-salon-_6.-pim2-2000_q-1152x1536.jpg 1152w\" \/><\/figure>\n\n\n<\/div>\n<div>\n<p>Sistema Cuina<\/p>\n<\/div>\n<\/div>\n<div>\n<h2>Sente-se com estilo<\/h2>\n<p>As cadeiras e os bancos podem fazer uma grande diferen\u00e7a no ambiente da sua cozinha ou sala de jantar; e uma boa escolha pode lev\u00e1-lo de um design sem gra\u00e7a para um cheio de personalidade e luxo.<\/p>\n<p>Por exemplo, a \u00e1rea de refei\u00e7\u00f5es desta cozinha projectada por F Alba. Se n\u00e3o acredita, tente imagin\u00e1-la com algumas cadeiras de madeira:<\/p>\n<\/div>\n<div>\n<div>\n\n\n<figure class=\"wp-block-image size-full ob-post-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1536\" height=\"2048\" sizes=\"auto, (max-width: 1536px) 100vw, 1536px\" src=\"https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/f_alba_-_cocina_verde_y_madera_vitoria_y_gola_negro_12.-pim2-2000_q.jpg\" alt=\"f_alba_-_cocina_verde_y_madera_vitoria_y_gola_negro_12.-pim2-2000_q\" class=\"wp-image-3259\" srcset=\"https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/f_alba_-_cocina_verde_y_madera_vitoria_y_gola_negro_12.-pim2-2000_q-jpg.avif 1536w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/f_alba_-_cocina_verde_y_madera_vitoria_y_gola_negro_12.-pim2-2000_q-225x300-jpg.avif 225w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/f_alba_-_cocina_verde_y_madera_vitoria_y_gola_negro_12.-pim2-2000_q-1152x1536-jpg.avif 1152w\" \/><\/figure>\n\n\n<\/div>\n<div>\n<p>F Alba<\/p>\n<\/div>\n<\/div>\n<div>\n<h2>Candeeiros com personalidade<\/h2>\n<p>Aqui fica uma dica para todos: se quer dar um toque de glamour sem investir uma fortuna, diferencie-se com candeeiros com personalidade!<\/p>\n<p>Independentemente do estilo que procura, h\u00e1 sempre uma op\u00e7\u00e3o para si. Por exemplo, neste projeto da Rivas S\u00e1nchez Carpinteros, optou-se por uma abordagem mais cl\u00e1ssica da ideia de luxo, instalando candeeiros suspensos em tons de prata por cima da bancada de m\u00e1rmore branco.<\/p>\n<\/div>\n<div>\n<div>\n\n\n<figure class=\"wp-block-image size-full ob-post-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1536\" height=\"2048\" sizes=\"auto, (max-width: 1536px) 100vw, 1536px\" src=\"https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/rivas_sanchez_carpinteros_-_alabama_natural_y_fenix_blanco_alaska_3.-pim2-2000_q.jpg\" alt=\"rivas_sanchez_carpinteros_-_alabama_natural_y_fenix_blanco_alaska_3.-pim2-2000_q\" class=\"wp-image-3260\" srcset=\"https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/rivas_sanchez_carpinteros_-_alabama_natural_y_fenix_blanco_alaska_3.-pim2-2000_q-jpg.avif 1536w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/rivas_sanchez_carpinteros_-_alabama_natural_y_fenix_blanco_alaska_3.-pim2-2000_q-225x300-jpg.avif 225w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/rivas_sanchez_carpinteros_-_alabama_natural_y_fenix_blanco_alaska_3.-pim2-2000_q-1152x1536-jpg.avif 1152w\" \/><\/figure>\n\n\n<\/div>\n<div>\n<p>Rivas S\u00e1nchez Carpinteros<\/p>\n<\/div>\n<\/div>\n<div>\n<p>Neste outro exemplo da Cuisine en Scene, foi dado um toque de estilo Mid Century atrav\u00e9s deste impressionante candeeiro geom\u00e9trico:<\/p>\n<\/div>\n<div>\n<div>\n\n\n<figure class=\"wp-block-image size-full ob-post-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1365\" height=\"2048\" sizes=\"auto, (max-width: 1365px) 100vw, 1365px\" src=\"https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/cusine-en-scene---cocina-negra-_18.-pim2-2000_q.jpg\" alt=\"cusine-en-scene---cocina-negra-_18.-pim2-2000_q\" class=\"wp-image-3261\" srcset=\"https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/cusine-en-scene---cocina-negra-_18.-pim2-2000_q-jpg.avif 1365w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/cusine-en-scene---cocina-negra-_18.-pim2-2000_q-200x300.jpg 200w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/cusine-en-scene---cocina-negra-_18.-pim2-2000_q-683x1024.jpg 683w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/cusine-en-scene---cocina-negra-_18.-pim2-2000_q-1024x1536.jpg 1024w\" \/><\/figure>\n\n\n<\/div>\n<div>\n<p>Cuisine en Scene<\/p>\n<\/div>\n<\/div>\n<div>\n<p>Mas se o que lhe agrada \u00e9 viver no presente, pode sempre optar por candeeiros de design moderno, como o deste projeto do nosso distribuidor Jorge Fern\u00e1ndez Grupo, que lhe d\u00e1 um toque ao cl\u00e1ssico tubo fluorescente.<\/p>\n<\/div>\n<div>\n<div>\n\n\n<figure class=\"wp-block-image size-full ob-post-image\"><img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1399\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\" src=\"https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/jorge_fernandez_grupo_-_fenix_gris_1.-pim2-2000_q-1.jpg\" alt=\"jorge_fernandez_grupo_-_fenix_gris_1.-pim2-2000_q-1\" class=\"wp-image-3262\" srcset=\"https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/jorge_fernandez_grupo_-_fenix_gris_1.-pim2-2000_q-1-jpg.avif 2000w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/jorge_fernandez_grupo_-_fenix_gris_1.-pim2-2000_q-1-1024x716-jpg.avif 1024w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/jorge_fernandez_grupo_-_fenix_gris_1.-pim2-2000_q-1-1536x1074-jpg.avif 1536w\" \/><\/figure>\n\n\n<\/div>\n<div>\n<p>Jorge Fern\u00e1ndez Grupo<\/p>\n<\/div>\n<\/div>\n<div>\n<h2>Apontar com luz<\/h2>\n<p>Terminamos a nossa lista com ainda mais luz: aquela que pode integrar no interior dos seus m\u00f3veis para acrescentar funcionalidade e\/ou destaque.<\/p>\n<p>Pode utiliz\u00e1-la para real\u00e7ar o calor de uma pe\u00e7a de mobili\u00e1rio e o seu toque vintage, como neste nicho instalado pelo Sistema Cuina:<\/p>\n<\/div>\n<div>\n<div>\n\n\n<figure class=\"wp-block-image size-full ob-post-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1536\" height=\"2048\" sizes=\"auto, (max-width: 1536px) 100vw, 1536px\" src=\"https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/sistema-cuina-cocina-verde-y-madera-con-isla-proyecto-burdeos-_2.-pim2-2000_q.jpg\" alt=\"sistema-cuina-cocina-verde-y-madera-con-isla-proyecto-burdeos-_2.-pim2-2000_q\" class=\"wp-image-3263\" srcset=\"https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/sistema-cuina-cocina-verde-y-madera-con-isla-proyecto-burdeos-_2.-pim2-2000_q-jpg.avif 1536w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/sistema-cuina-cocina-verde-y-madera-con-isla-proyecto-burdeos-_2.-pim2-2000_q-225x300.jpg 225w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/sistema-cuina-cocina-verde-y-madera-con-isla-proyecto-burdeos-_2.-pim2-2000_q-1152x1536.jpg 1152w\" \/><\/figure>\n\n\n<\/div>\n<div>\n<p>Sistema Cuina<\/p>\n<\/div>\n<\/div>\n<div>\n<p>Ou para dar um toque elegante a uma cozinha r\u00fastica, como no arm\u00e1rio expositor deste projeto da NM Cuines:<\/p>\n<\/div>\n<div>\n<div>\n\n\n<figure class=\"wp-block-image size-full ob-post-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1536\" height=\"2048\" sizes=\"auto, (max-width: 1536px) 100vw, 1536px\" src=\"https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/nm-cuines---cocina-madera-con-isla-y-vitrina-de-cristal-_1.-pim2-2000_q.jpg\" alt=\"nm-cuines---cocina-madera-con-isla-y-vitrina-de-cristal-_1.-pim2-2000_q\" class=\"wp-image-3264\" srcset=\"https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/nm-cuines---cocina-madera-con-isla-y-vitrina-de-cristal-_1.-pim2-2000_q-jpg.avif 1536w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/nm-cuines---cocina-madera-con-isla-y-vitrina-de-cristal-_1.-pim2-2000_q-225x300.jpg 225w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/nm-cuines---cocina-madera-con-isla-y-vitrina-de-cristal-_1.-pim2-2000_q-1152x1536.jpg 1152w\" \/><\/figure>\n\n\n<\/div>\n<div>\n<p>NM Cuines<\/p>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>H\u00e1 muito que as cozinhas deixaram de ser um mero local de trabalho, com a est\u00e9tica subordinada \u00e0 funcionalidade e longe dos olhares dos visitantes que chegam a casa.\u00a0 Atualmente, \u00e9 um espa\u00e7o onde queremos n\u00e3o s\u00f3 viver e sentirmo-nos bem, mas tamb\u00e9m exibi-lo com orgulho e integr\u00e1-lo na nossa casa. Talvez seja por isso [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14382,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1333],"tags":[],"class_list":["post-14381","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-consejos"],"_links":{"self":[{"href":"https:\/\/obcocinas.es\/pt\/wp-json\/wp\/v2\/posts\/14381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/obcocinas.es\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/obcocinas.es\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/obcocinas.es\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/obcocinas.es\/pt\/wp-json\/wp\/v2\/comments?post=14381"}],"version-history":[{"count":1,"href":"https:\/\/obcocinas.es\/pt\/wp-json\/wp\/v2\/posts\/14381\/revisions"}],"predecessor-version":[{"id":15082,"href":"https:\/\/obcocinas.es\/pt\/wp-json\/wp\/v2\/posts\/14381\/revisions\/15082"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/obcocinas.es\/pt\/wp-json\/wp\/v2\/media\/14382"}],"wp:attachment":[{"href":"https:\/\/obcocinas.es\/pt\/wp-json\/wp\/v2\/media?parent=14381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/obcocinas.es\/pt\/wp-json\/wp\/v2\/categories?post=14381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/obcocinas.es\/pt\/wp-json\/wp\/v2\/tags?post=14381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}