{"id":14337,"date":"2025-01-12T00:00:00","date_gmt":"2025-01-11T23:00:00","guid":{"rendered":"https:\/\/obcocinas.es\/estantes-e-moveis-visto-um-novo-ar-para-a-sua-cozinha\/"},"modified":"2025-12-03T09:12:54","modified_gmt":"2025-12-03T08:12:54","slug":"estantes-e-moveis-visto-um-novo-ar-para-a-sua-cozinha","status":"publish","type":"post","link":"https:\/\/obcocinas.es\/pt\/blog\/estantes-e-moveis-visto-um-novo-ar-para-a-sua-cozinha\/","title":{"rendered":"Estantes e m\u00f3veis expostos: um novo visual para a sua cozinha!"},"content":{"rendered":"<div>\n<p>Se est\u00e1 a planear a sua cozinha, tome nota desta tend\u00eancia! A incorpora\u00e7\u00e3o de m\u00f3veis e prateleiras expostos \u00e9 uma op\u00e7\u00e3o ideal para quem procura um ar fresco, leve e decorativo nas suas cozinhas. Quer se trate de uma cozinha aberta ou fechada, este tipo de mobili\u00e1rio oferece grandes vantagens e infinitas possibilidades de decora\u00e7\u00e3o e organiza\u00e7\u00e3o. N\u00f3s dizemos-lhe como integr\u00e1-los com sucesso!<\/p>\n<p>Uma das principais vantagens de optar por prateleiras ou m\u00f3veis sem portas \u00e9 a sensa\u00e7\u00e3o de amplitude que geram. Ao eliminar as estruturas fechadas, o ambiente fica muito mais espa\u00e7oso e arejado (algo essencial em cozinhas pequenas).\u00a0<\/p>\n<p>Al\u00e9m disso, permitem expor objectos decorativos, como lou\u00e7a de design, vasos ou pequenos electrodom\u00e9sticos, convertendo objectos do quotidiano em parte da decora\u00e7\u00e3o; como neste projeto do nosso distribuidor Muebles Fran:<\/p>\n<\/div>\n<div>\n<div>\u00a0<\/div>\n<\/div>\n\n\n<figure class=\"wp-block-image size-full ob-post-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1365\" height=\"2048\" sizes=\"auto, (max-width: 1365px) 100vw, 1365px\" src=\"https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/muebles_fran_-_cocina_negra_y_madera_20.-pim2-2000_q.jpg\" alt=\"muebles_fran_-_cocina_negra_y_madera_20.-pim2-2000_q\" class=\"wp-image-3946\" srcset=\"https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/muebles_fran_-_cocina_negra_y_madera_20.-pim2-2000_q-jpg.avif 1365w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/muebles_fran_-_cocina_negra_y_madera_20.-pim2-2000_q-200x300-jpg.avif 200w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/muebles_fran_-_cocina_negra_y_madera_20.-pim2-2000_q-683x1024-jpg.avif 683w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/muebles_fran_-_cocina_negra_y_madera_20.-pim2-2000_q-1024x1536-jpg.avif 1024w\" \/><\/figure>\n\n\n<\/div>\n<div>\n<p>Muebles Fran<\/p>\n<\/div>\n<\/div>\n<div>\n<p>Por outro lado, estas pe\u00e7as de mobili\u00e1rio s\u00e3o extremamente vers\u00e1teis. Se, por exemplo, gosta de cozinhas de estilo r\u00fastico, uma prateleira de madeira desgastada dar\u00e1 um toque acolhedor e natural. Se, por outro lado, preferir um design mais minimalista e contempor\u00e2neo, as estruturas met\u00e1licas ou lacadas a preto ser\u00e3o os seus melhores aliados.<\/p>\n<p>Neste projeto do Sistema Cuina, a inclus\u00e3o de prateleiras flutuantes foi uma \u00f3ptima forma de dar um toque acolhedor e moderno \u00e0 cozinha, al\u00e9m de ser uma excelente forma de aproveitar ao m\u00e1ximo as paredes sem sobrecarregar visualmente a divis\u00e3o:<\/p>\n<\/div>\n<div>\n<div>\n\n\n<figure class=\"wp-block-image size-full ob-post-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1364\" height=\"2048\" sizes=\"auto, (max-width: 1364px) 100vw, 1364px\" src=\"https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/sistema_cuina_-_cocina_verde_y_madera_7.-pim2-2000_q.jpg\" alt=\"sistema_cuina_-_cocina_verde_y_madera_7.-pim2-2000_q\" class=\"wp-image-3947\" srcset=\"https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/sistema_cuina_-_cocina_verde_y_madera_7.-pim2-2000_q-jpg.avif 1364w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/sistema_cuina_-_cocina_verde_y_madera_7.-pim2-2000_q-200x300-jpg.avif 200w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/sistema_cuina_-_cocina_verde_y_madera_7.-pim2-2000_q-682x1024-jpg.avif 682w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/sistema_cuina_-_cocina_verde_y_madera_7.-pim2-2000_q-1023x1536-jpg.avif 1023w\" \/><\/figure>\n\n\n<\/div>\n<div>\n<p>Sistema Cuina<\/p>\n<\/div>\n<\/div>\n<div>\n<p>A inclus\u00e3o de prateleiras tamb\u00e9m tem uma componente pr\u00e1tica. Ter tudo \u00e0 vista e ao alcance das m\u00e3os torna as tarefas di\u00e1rias, como cozinhar ou limpar, muito mais c\u00f3modas. No entanto, \u00e9 importante manter a ordem e a harmonia no que se exp\u00f5e. Uma boa ideia \u00e9 combinar elementos \u00fateis com pormenores decorativos: coloque frascos de vidro com ingredientes, livros de receitas, pequenas plantas ou cestos de fibras naturais para organizar os objectos menos est\u00e9ticos.<\/p>\n<\/div>\n<div>\n<div>\n\n\n<figure class=\"wp-block-image size-full ob-post-image\"><img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1333\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\" src=\"https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/jorge_fernandez_-_lagos_blanco_3.-pim2-2000_q.jpeg\" alt=\"jorge_fernandez_-_lagos_blanco_3.-pim2-2000_q\" class=\"wp-image-3948\" srcset=\"https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/jorge_fernandez_-_lagos_blanco_3.-pim2-2000_q-jpeg.avif 2000w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/jorge_fernandez_-_lagos_blanco_3.-pim2-2000_q-1024x682-jpeg.avif 1024w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/jorge_fernandez_-_lagos_blanco_3.-pim2-2000_q-1536x1024-jpeg.avif 1536w\" \/><\/figure>\n\n\n<\/div>\n<div>\n<p>JF Cocinas<\/p>\n<\/div>\n<\/div>\n<div>\n<p>Em cozinhas fechadas, as unidades expostas podem atuar como pontos focais que quebram a monotonia das unidades com porta. Por exemplo, uma pequena prateleira por cima da bancada (como no exemplo da JF Cocinas acima) ou junto a um exaustor pode ser utilizada para guardar especiarias ou utens\u00edlios bonitos.<\/p>\n<p>Por outro lado, nas cozinhas abertas, onde o design flui para a \u00e1rea de jantar ou de estar, as prateleiras podem ser utilizadas para integrar visualmente os espa\u00e7os. Uma prateleira com livros e pe\u00e7as decorativas tornar\u00e1 a sua cozinha mais acolhedora e personalizada.<\/p>\n<\/div>\n<div>\n<div>\n\n\n<figure class=\"wp-block-image size-full ob-post-image\"><img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1334\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\" src=\"https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/apal_-_cocina_madera_encimera_negra_amazonas_8.-pim2-2000_q.jpg\" alt=\"apal_-_cocina_madera_encimera_negra_amazonas_8.-pim2-2000_q\" class=\"wp-image-3949\" srcset=\"https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/apal_-_cocina_madera_encimera_negra_amazonas_8.-pim2-2000_q-jpg.avif 2000w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/apal_-_cocina_madera_encimera_negra_amazonas_8.-pim2-2000_q-1024x683-jpg.avif 1024w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/apal_-_cocina_madera_encimera_negra_amazonas_8.-pim2-2000_q-1536x1025-jpg.avif 1536w\" \/><\/figure>\n\n\n<\/div>\n<div>\n<p>Apal<\/p>\n<\/div>\n<\/div>\n<div>\n<p>n\u00e3o se limite \u00e0s paredes! Os arm\u00e1rios inferiores expostos s\u00e3o uma excelente op\u00e7\u00e3o para guardar cestos, garrafas ou utens\u00edlios de cozinha de grandes dimens\u00f5es, ou aqueles a que se pretende ter f\u00e1cil acesso, desimpedindo assim a bancada de trabalho. Por exemplo, este pormenor de um projeto Sistema Cuina:<\/p>\n<\/div>\n<div>\n<div>\n\n\n<figure class=\"wp-block-image size-full ob-post-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1537\" height=\"2048\" sizes=\"auto, (max-width: 1537px) 100vw, 1537px\" src=\"https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/sistema_cuina_-_cocina_blanca_con_etalles_en_madera_de_roble_y_porcelanico_gris_21.-pim2-2000_q.jpg\" alt=\"sistema_cuina_-_cocina_blanca_con_etalles_en_madera_de_roble_y_porcelanico_gris_21.-pim2-2000_q\" class=\"wp-image-3950\" srcset=\"https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/sistema_cuina_-_cocina_blanca_con_etalles_en_madera_de_roble_y_porcelanico_gris_21.-pim2-2000_q-jpg.avif 1537w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/sistema_cuina_-_cocina_blanca_con_etalles_en_madera_de_roble_y_porcelanico_gris_21.-pim2-2000_q-225x300-jpg.avif 225w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/sistema_cuina_-_cocina_blanca_con_etalles_en_madera_de_roble_y_porcelanico_gris_21.-pim2-2000_q-769x1024.jpg 769w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/sistema_cuina_-_cocina_blanca_con_etalles_en_madera_de_roble_y_porcelanico_gris_21.-pim2-2000_q-1153x1536-jpg.avif 1153w\" \/><\/figure>\n\n\n<\/div>\n<div>\n<p>Sistema Cuina<\/p>\n<\/div>\n<\/div>\n<div>\n<p>Se estiver preocupado com a manuten\u00e7\u00e3o, opte por materiais f\u00e1ceis de limpar. Em todo o caso, o segredo \u00e9 n\u00e3o sobrecarregar as prateleiras. Deixe espa\u00e7os vazios para que a composi\u00e7\u00e3o respire e n\u00e3o crie um caos no ambiente. Esta ideia tamb\u00e9m se aplica se decidir instalar m\u00f3veis inferiores, que funcionam muito bem para organizar a loi\u00e7a ou os utens\u00edlios do dia a dia.<\/p>\n<p>As estantes e m\u00f3veis expostos s\u00e3o tamb\u00e9m uma solu\u00e7\u00e3o perfeita para quem gosta de mudar a decora\u00e7\u00e3o com frequ\u00eancia. Sem portas ou estruturas que limitem o que pode ser exposto, \u00e9 f\u00e1cil mudar o estilo com as esta\u00e7\u00f5es do ano ou as tend\u00eancias actuais.<\/p>\n<\/div>\n<div>\n<div>\n\n\n<figure class=\"wp-block-image size-full ob-post-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1537\" height=\"2048\" sizes=\"auto, (max-width: 1537px) 100vw, 1537px\" src=\"https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/studilo_daless_y_agostina_dalo_-_cocina_blanca_y_madera_con_mesa_comedor_7.-pim2-2000_q.jpg\" alt=\"studilo_daless_y_agostina_dalo_-_cocina_blanca_y_madera_con_mesa_comedor_7.-pim2-2000_q\" class=\"wp-image-3951\" srcset=\"https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/studilo_daless_y_agostina_dalo_-_cocina_blanca_y_madera_con_mesa_comedor_7.-pim2-2000_q-jpg.avif 1537w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/studilo_daless_y_agostina_dalo_-_cocina_blanca_y_madera_con_mesa_comedor_7.-pim2-2000_q-225x300-jpg.avif 225w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/studilo_daless_y_agostina_dalo_-_cocina_blanca_y_madera_con_mesa_comedor_7.-pim2-2000_q-769x1024-jpg.avif 769w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/studilo_daless_y_agostina_dalo_-_cocina_blanca_y_madera_con_mesa_comedor_7.-pim2-2000_q-1153x1536-jpg.avif 1153w\" \/><\/figure>\n\n\n<\/div>\n<div>\n<p>Studio DAless<\/p>\n<\/div>\n<\/div>\n<div>\n<p>Em suma, incluir prateleiras e arm\u00e1rios expostos na cozinha \u00e9 uma \u00f3ptima maneira de dar \u00e0 sua casa um aspeto fresco, moderno e funcional. Quer prefira um estilo minimalista, industrial ou r\u00fastico, estas estruturas adaptam-se a qualquer design e oferecem infinitas possibilidades decorativas. Basta um pouco de criatividade e bom gosto para transformar a sua cozinha num espa\u00e7o cheio de personalidade.<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Se est\u00e1 a planear a sua cozinha, tome nota desta tend\u00eancia! A incorpora\u00e7\u00e3o de m\u00f3veis e prateleiras expostos \u00e9 uma op\u00e7\u00e3o ideal para quem procura um ar fresco, leve e decorativo nas suas cozinhas. Quer se trate de uma cozinha aberta ou fechada, este tipo de mobili\u00e1rio oferece grandes vantagens e infinitas possibilidades de decora\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14338,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1334],"tags":[],"class_list":["post-14337","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inspiracion"],"_links":{"self":[{"href":"https:\/\/obcocinas.es\/pt\/wp-json\/wp\/v2\/posts\/14337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/obcocinas.es\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/obcocinas.es\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/obcocinas.es\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/obcocinas.es\/pt\/wp-json\/wp\/v2\/comments?post=14337"}],"version-history":[{"count":1,"href":"https:\/\/obcocinas.es\/pt\/wp-json\/wp\/v2\/posts\/14337\/revisions"}],"predecessor-version":[{"id":14995,"href":"https:\/\/obcocinas.es\/pt\/wp-json\/wp\/v2\/posts\/14337\/revisions\/14995"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/obcocinas.es\/pt\/wp-json\/wp\/v2\/media\/14338"}],"wp:attachment":[{"href":"https:\/\/obcocinas.es\/pt\/wp-json\/wp\/v2\/media?parent=14337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/obcocinas.es\/pt\/wp-json\/wp\/v2\/categories?post=14337"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/obcocinas.es\/pt\/wp-json\/wp\/v2\/tags?post=14337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}