{"id":9163,"date":"2025-11-14T15:42:15","date_gmt":"2025-11-14T14:42:15","guid":{"rendered":"https:\/\/dev.obcocinas.com\/tienda\/matobra-coimbra-coimbra\/"},"modified":"2026-03-16T10:14:09","modified_gmt":"2026-03-16T09:14:09","slug":"matobra-coimbra-coimbra","status":"publish","type":"tienda","link":"https:\/\/obcocinas.es\/fr\/magasin\/matobra-coimbra-coimbra\/","title":{"rendered":"Matobra Coimbra"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Leve a sua cozinha a um novo n\u00edvel com a Matobra<\/h3>\n\n\n\n<p>O trabalho da Matobra come\u00e7a no seu showroom com um servi\u00e7o de aconselhamento personalizado sobre materiais e acabamentos, solu\u00e7\u00f5es de arruma\u00e7\u00e3o e outros elementos, como a ilumina\u00e7\u00e3o integrada, que tornar\u00e3o a sua nova cozinha mais funcional e pessoal. Depois de visitarem o espa\u00e7o e verificarem as medidas, v\u00e3o desenvolver o projeto da cozinha em 3D para que tenha uma ideia fiel do resultado. Uma vez aprovado, m\u00e3os \u00e0 obra! A Matobra encarrega-se de instalar todos os m\u00f3veis, bancadas e torneiras da sua cozinha, bem como todos os eletrodom\u00e9sticos que adquirir na loja. A sua experi\u00eancia \u00e9 a melhor garantia de que s\u00f3 ter\u00e1 de se preocupar em pensar no menu com que vai inaugurar a sua nova cozinha.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Leve a sua cozinha a um novo n\u00edvel com a Matobra O trabalho da Matobra come\u00e7a no seu showroom com um servi\u00e7o de aconselhamento personalizado sobre materiais e acabamentos, solu\u00e7\u00f5es de arruma\u00e7\u00e3o e outros elementos, como a ilumina\u00e7\u00e3o integrada, que tornar\u00e3o a sua nova cozinha mais funcional e pessoal. Depois de visitarem o espa\u00e7o e [&hellip;]<\/p>\n","protected":false},"featured_media":7103,"template":"","ciudad":[745],"provincia":[716],"pais":[451],"class_list":["post-9163","tienda","type-tienda","status-publish","has-post-thumbnail","hentry","ciudad-coimbra","provincia-coimbra","pais-portugal"],"_links":{"self":[{"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/tienda\/9163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/tienda"}],"about":[{"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/types\/tienda"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/media\/7103"}],"wp:attachment":[{"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/media?parent=9163"}],"wp:term":[{"taxonomy":"ciudad","embeddable":true,"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/ciudad?post=9163"},{"taxonomy":"provincia","embeddable":true,"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/provincia?post=9163"},{"taxonomy":"pais","embeddable":true,"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/pais?post=9163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}