{"id":10479,"date":"2025-11-12T17:17:42","date_gmt":"2025-11-12T16:17:42","guid":{"rendered":"https:\/\/dev.obcocinas.com\/tienda\/afa-ventanas-y-cocinas-real-de-gandia\/"},"modified":"2025-11-30T22:11:19","modified_gmt":"2025-11-30T21:11:19","slug":"afa-ventanas-y-cocinas-real-de-gandia","status":"publish","type":"tienda","link":"https:\/\/obcocinas.es\/fr\/magasin\/afa-ventanas-y-cocinas-real-de-gandia\/","title":{"rendered":"AFA Ventanas y Cocinas"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Cocinas en Gand\u00eda<\/h3>\n\n\n\n<p>\u00bfHas decidido que ya es hora de cambiar tu cocina? Pues tienes que contar con AFA Ventanas y Cocinas, los mayores expertos de cocinas en Gand\u00eda. Llevan m\u00e1s de cuatro d\u00e9cadas trabajando en el sector del h\u00e1bitat y especializ\u00e1ndose en ventanas y cocinas en Gand\u00eda. \u00bfLo mejor de AFA Ventanas y Cocinas? Su compromiso con la calidad y la pasi\u00f3n que sienten por su trabajo. Los profesionales que conforman el equipo de AFA Ventanas y Cocinas viven y se esfuerzan en cada proyecto como si fuera el suyo propio. Porque saben de la importancia que un espacio como la cocina, tiene en el d\u00eda a d\u00eda de las personas. As\u00ed que si sientes que tu cocina necesita transformarse en un espacio m\u00e1s funcional y con una est\u00e9tica m\u00e1s actual, AFA Ventanas y Cocinas es el lugar ideal.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Tienda de distribuci\u00f3n de muebles de OB Cocinas en Gand\u00eda<\/h3>\n\n\n\n<p>En AFA Ventanas y Cocinas encontrar\u00e1s la inspiraci\u00f3n que necesitas para tu nueva cocina y tambi\u00e9n todas las soluciones a tus necesidades. All\u00ed sabr\u00e1n ofrecerte una cocina a medida, nunca mejor dicho. Porque las cocinas no solo son muebles y electrodom\u00e9sticos. Las cocinas son espacios en los que vivir, disfrutar y crear recuerdos. Son el coraz\u00f3n de los hogares. No dudes ni un segundo m\u00e1s y ven a conocer las cocinas en Gand\u00eda que AFA Ventanas y Cocinas tiene preparadas para ti. Te esperan en la Avenida de Valencia, n\u00famero 16. Su horario de atenci\u00f3n al p\u00fablico es de lunes a viernes, 8 a 13:30 y de 15:30 a 18:30 horas y los s\u00e1bados con cita previa. [&#8230;]<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Mobiliario de cocina a medida<\/h3>\n\n\n\n<p>\u00a1Y t\u00fa qu\u00e9 cre\u00edas que encontrar tus muebles de cocina en Gand\u00eda iba a ser complicado! AFA Ventanas y Cocinas es distribuidor de OB Cocinas en Gand\u00eda y, como tal, pone a tu disposici\u00f3n todo nuestro cat\u00e1logo de muebles para que puedas inspirarte y visualizar tu cocina ideal. Sus interioristas y t\u00e9cnicos estudiar\u00e1n tu caso, te mostrar\u00e1n las mejores opciones que te permitir\u00e1n aprovechar mejor el espacio, sacarle el m\u00e1ximo partido posible a la luz natural de la que dispongas y encontrar el estilo que mejor combine con el resto de la casa y tambi\u00e9n con tu propia finalidad. \u00bfPrefieres las cocinas minimalistas, modernas o con aires industriales? \u00bfO quiz\u00e1s buscas una est\u00e9tica m\u00e1s tradicional y r\u00fastica, buscando un efecto m\u00e1s acogedor? D\u00e9jate llevar por la intuici\u00f3n, con los muebles de OB Cocinas y el asesoramiento de AFA Ventanas y Cocinas el \u00e9xito est\u00e1 m\u00e1s que asegurado. Adem\u00e1s de esta variad\u00edsima oferta de muebles de cocina en Gand\u00eda en AFA Ventanas y Cocinas tambi\u00e9n se encargan de poner en marcha el proyecto, ocup\u00e1ndose de toda la instalaci\u00f3n y montaje, asegur\u00e1ndose de que todo est\u00e9 correctamente colocado y funcionando. Esta atenci\u00f3n al detalle y tu tranquilidad por el trabajo bien hecho es una de las grandes ventajas que tiene contar con el equipo de AFA Ventanas y Cocinas para la reforma de tu cocina en Gand\u00eda. Solo tienes que pasarte por all\u00ed para poner en marcha tu proyecto de cocina, \u00a1y muy pronto podr\u00e1s hacer M\u00e1s Vida en la Cocina!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cocinas en Gand\u00eda \u00bfHas decidido que ya es hora de cambiar tu cocina? Pues tienes que contar con AFA Ventanas y Cocinas, los mayores expertos de cocinas en Gand\u00eda. Llevan m\u00e1s de cuatro d\u00e9cadas trabajando en el sector del h\u00e1bitat y especializ\u00e1ndose en ventanas y cocinas en Gand\u00eda. \u00bfLo mejor de AFA Ventanas y Cocinas? [&hellip;]<\/p>\n","protected":false},"featured_media":7070,"template":"","ciudad":[1027],"provincia":[571],"pais":[416],"class_list":["post-10479","tienda","type-tienda","status-publish","has-post-thumbnail","hentry","ciudad-real-de-gandia","provincia-valencia","pais-espana"],"_links":{"self":[{"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/tienda\/10479","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/tienda"}],"about":[{"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/types\/tienda"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/media\/7070"}],"wp:attachment":[{"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/media?parent=10479"}],"wp:term":[{"taxonomy":"ciudad","embeddable":true,"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/ciudad?post=10479"},{"taxonomy":"provincia","embeddable":true,"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/provincia?post=10479"},{"taxonomy":"pais","embeddable":true,"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/pais?post=10479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}