{"id":10440,"date":"2025-11-12T21:48:19","date_gmt":"2025-11-12T20:48:19","guid":{"rendered":"https:\/\/dev.obcocinas.com\/tienda\/casami-muebles-infiesto-castrillon\/"},"modified":"2025-11-30T22:10:56","modified_gmt":"2025-11-30T21:10:56","slug":"casami-muebles-infiesto-castrillon","status":"publish","type":"tienda","link":"https:\/\/obcocinas.es\/fr\/magasin\/casami-muebles-infiesto-castrillon\/","title":{"rendered":"Casami Muebles Infiesto"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Muebles de cocina en Avil\u00e9s<\/h3>\n\n\n\n<p>\u00bfEst\u00e1s buscando muebles de cocina en Avil\u00e9s? \u00a1Deja de buscar, est\u00e1n en Casami Muebles Infiesto! De hecho, en su tienda encontrar\u00e1s mobiliario para toda la casa; ya que esta empresa lleva m\u00e1s de 50 a\u00f1os creando espacios acogedores para los hogares de sus clientes con piezas exclusivas de fabricantes espa\u00f1oles. Con ellos podr\u00e1s amueblar salones, ba\u00f1os, oficinas&#8230; y, c\u00f3mo no, cocinas en Avil\u00e9s. Adem\u00e1s de su cuidada selecci\u00f3n de mobiliario, tambi\u00e9n son especialistas en reformas. Pero antes de cont\u00e1rtelo, d\u00e9janos decirte d\u00f3nde puedes encontrarlos.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Tu tienda de muebles de cocina en Avil\u00e9s<\/h3>\n\n\n\n<p>Esta tienda de muebles de cocina en Avil\u00e9s es muy conocida. De hecho, si vives en esa localidad es m\u00e1s que probable que hayas pasado delante de su gran escaparate alguna que otra vez. Y no solo por el tiempo que llevan dedicados a la venta de mobiliario, sino tambi\u00e9n por encontrarse en una zona muy c\u00e9ntrica (para que te hagas una idea, est\u00e1 solo a 10 minutos andando de la Plaza de Espa\u00f1a). Concretamente, tu tienda de muebles de cocina en Avil\u00e9s se encuentra en la calle Doctor Mara\u00f1on n\u00famero 8, muy cerca del Parque Ferrera. All\u00ed podr\u00e1s encontrarlos de lunes a viernes de 9:30 a 13 horas y de 16:30 a 20 horas. Los s\u00e1bados abren en horario de ma\u00f1ana, de 9:30 a 13 horas. [&#8230;]<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Visita nuestro estudio de cocinas con dise\u00f1os exclusivos<\/h3>\n\n\n\n<p>Aunque en sus inicios empresariales esta tienda de muebles se dedic\u00f3 a la selecci\u00f3n y venta de mobiliario para el hogar; Casami Muebles Infiesto fue ampliando poco a poco su actividad comercial hasta convertirse en lo que es hoy: un referente en mobiliario y reformas integrales en toda Asturias. Poco a poco, y gracias a la experiencia en el asesoramiento sobre mobiliario, fue ampliando su cat\u00e1logo de materiales y elementos decorativos, as\u00ed como su equipo de profesionales. Actualmente, su plantilla est\u00e1 formada tambi\u00e9n por interioristas cualificados y expertos trabajadores del sector de las reformas. Su personal trabajar\u00e1 de manera conjunta con seriedad, eficacia y rigor para ocuparse de cualquier proyecto de cocinas en Avil\u00e9s, sin importar la complejidad o envergadura. Se ocupan de todo el proceso, desde el dise\u00f1o en 3D de esa cocina con la que tanto tiempo llevas so\u00f1ando; hasta de todas las instalaciones necesarias para la entrega llave en mano. En el camino, c\u00f3mo no, te asesorar\u00e1n en la elecci\u00f3n de nuestros muebles de cocina en Avil\u00e9s para que aciertes s\u00ed o s\u00ed. En su tienda encontrar\u00e1s una exposici\u00f3n variada de nuestras cocinas; adem\u00e1s de los cat\u00e1logos y un amplio muestrario de materiales, colores y acabados. \u00bfA qu\u00e9 esperas para visitarlos?<\/p>\n\n\n\n<p><canvas width=\"1280\" height=\"1\"><\/canvas><\/p>\n\n\n\n<p><a href=\"https:\/\/obcocinas.es\/nuestras-cocinas\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Muebles de cocina en Avil\u00e9s \u00bfEst\u00e1s buscando muebles de cocina en Avil\u00e9s? \u00a1Deja de buscar, est\u00e1n en Casami Muebles Infiesto! De hecho, en su tienda encontrar\u00e1s mobiliario para toda la casa; ya que esta empresa lleva m\u00e1s de 50 a\u00f1os creando espacios acogedores para los hogares de sus clientes con piezas exclusivas de fabricantes espa\u00f1oles. [&hellip;]<\/p>\n","protected":false},"featured_media":7082,"template":"","ciudad":[1039],"provincia":[688],"pais":[],"class_list":["post-10440","tienda","type-tienda","status-publish","has-post-thumbnail","hentry","ciudad-castrillon","provincia-asturias"],"_links":{"self":[{"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/tienda\/10440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/tienda"}],"about":[{"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/types\/tienda"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/media\/7082"}],"wp:attachment":[{"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/media?parent=10440"}],"wp:term":[{"taxonomy":"ciudad","embeddable":true,"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/ciudad?post=10440"},{"taxonomy":"provincia","embeddable":true,"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/provincia?post=10440"},{"taxonomy":"pais","embeddable":true,"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/pais?post=10440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}