{"id":10287,"date":"2025-11-13T16:17:28","date_gmt":"2025-11-13T15:17:28","guid":{"rendered":"https:\/\/dev.obcocinas.com\/tienda\/madecort-puerto-real\/"},"modified":"2025-11-30T22:09:37","modified_gmt":"2025-11-30T21:09:37","slug":"madecort-puerto-real","status":"publish","type":"tienda","link":"https:\/\/obcocinas.es\/fr\/magasin\/madecort-puerto-real\/","title":{"rendered":"Madecort"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Cocinas en Puerto Real<\/h3>\n\n\n\n<p>\u00bfTu cocina ya no es lo que era y no cumple tus necesidades? \u00bfNecesitas un cambio radical? Apunta este nombre: Madecort, el distribuidor de nuestros muebles en Puerto Real. Estamos convencidos de que su equipo no te va a defraudar. Y es que comparten con nosotros una misma filosof\u00eda: la de poner su grano de arena para crear espacios en los que la vida fluya de manera natural y agradable. Y no solo eso, su atenci\u00f3n al detalle y el asesoramiento personal que dan a cada uno de sus clientes los ha convertido en un referente en el dise\u00f1o y montaje de muebles de cocina en toda la Bah\u00eda de C\u00e1diz. \u00bfQuieres saber m\u00e1s sobre el distribuidor de OB Cocinas en Puerto Real?<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Visita Madecort<\/h3>\n\n\n\n<p>Para conocer mejor a nuestro distribuidor, te recomendamos encarecidamente que vayas a visitarlo; pues su establecimiento habla por s\u00ed mismo. Se encuentra situado estrat\u00e9gicamente en el Pol\u00edgono Industrial Tres Caminos, en la calle Mojarra n\u00famero 10. Se trata de una zona industrial y comercial que si bien est\u00e1 en Puerto Real; queda a un paso de San Fernando y Chiclana. Por ello, Madecort es tu opci\u00f3n si vives en la Bah\u00eda de C\u00e1diz.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Empieza a hacer M\u00e1s Vida en la Cocina<\/h3>\n\n\n\n<p>En Madecort saben muy bien que la reforma de una cocina no es algo que sus clientes se tomen a la ligera, sino que se trata de una gran decisi\u00f3n en sus vidas y que va a afectar directamente a su d\u00eda a d\u00eda. Por eso, todo el equipo est\u00e1 comprometido con un asesoramiento personal y cercano desde el mismo momento en el que un cliente entra en su showroom. Te ense\u00f1ar\u00e1n las diferentes opciones disponibles en lo que respecta a materiales, acabados, sistemas de almacenaje y apertura, soluciones de ergonom\u00eda, planificaci\u00f3n\u2026 y lo que es mejor, te acompa\u00f1ar\u00e1n en la toma de decisiones para que aciertes s\u00ed o s\u00ed y puedas empezar a hacer M\u00e1s Vida en la Cocina.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cocinas en Puerto Real \u00bfTu cocina ya no es lo que era y no cumple tus necesidades? \u00bfNecesitas un cambio radical? Apunta este nombre: Madecort, el distribuidor de nuestros muebles en Puerto Real. Estamos convencidos de que su equipo no te va a defraudar. Y es que comparten con nosotros una misma filosof\u00eda: la de [&hellip;]<\/p>\n","protected":false},"featured_media":7070,"template":"","ciudad":[916],"provincia":[553],"pais":[416],"class_list":["post-10287","tienda","type-tienda","status-publish","has-post-thumbnail","hentry","ciudad-puerto-real","provincia-cadiz","pais-espana"],"_links":{"self":[{"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/tienda\/10287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/tienda"}],"about":[{"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/types\/tienda"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/media\/7070"}],"wp:attachment":[{"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/media?parent=10287"}],"wp:term":[{"taxonomy":"ciudad","embeddable":true,"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/ciudad?post=10287"},{"taxonomy":"provincia","embeddable":true,"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/provincia?post=10287"},{"taxonomy":"pais","embeddable":true,"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/pais?post=10287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}