{"id":10101,"date":"2025-11-14T15:14:47","date_gmt":"2025-11-14T14:14:47","guid":{"rendered":"https:\/\/dev.obcocinas.com\/tienda\/xfreixer-mataro-mataro\/"},"modified":"2025-11-30T22:08:03","modified_gmt":"2025-11-30T21:08:03","slug":"xfreixer-mataro-mataro","status":"publish","type":"tienda","link":"https:\/\/obcocinas.es\/fr\/magasin\/xfreixer-mataro-mataro\/","title":{"rendered":"Xfreixer Matar\u00f3"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Tienda de cocinas en Matar\u00f3<\/h3>\n\n\n\n<p>Si est\u00e1s buscando muebles de cocina en Matar\u00f3 no puedes dejar de visitar XFreixer. Dise\u00f1o de alto nivel y todas las colecciones de OB Cocinas a tu disposici\u00f3n. Adem\u00e1s de ser unos de los mayores expertos en cocinas en Madrid con una amplia experiencia en dise\u00f1o y mobiliario, en XFreixer trabajan ajust\u00e1ndose a la perfecci\u00f3n a los requisitos de los clientes, desarrollando proyectos a medida, haciendo de cada cocina un espacio \u00fanico y personal: un espacio para vivir. Es el momento de poner en marcha esa reforma a la que llevas tanto tiempo d\u00e1ndole vueltas y XFreixer es tu tienda de cocinas en Matar\u00f3.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Bienvenido a tu tienda de muebles de cocina en Matar\u00f3<\/h3>\n\n\n\n<p>XFreixer es mucho m\u00e1s que una tienda de muebles de cocina en Matar\u00f3. Y es que el grado de personalizaci\u00f3n y el alto nivel de dise\u00f1o que marcan sus cocinas los hacen ser un referente de creatividad, profesionalidad y calidad en el sector de muebles de cocina en Matar\u00f3. Si quieres comprobar por t\u00ed mismo lo que aqu\u00ed te estamos contando puedes pasarte por su tienda en Via Europa, n\u00famero 153. All\u00ed te atender\u00e1n de lunes a viernes, 9 a 13 horas y de 16 a 19:30 horas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Conoce nuestro estudio de cocinas de dise\u00f1o<\/h3>\n\n\n\n<p>En XFreixer vas a encontrar todo lo que necesitas para llevar a cabo la reforma de tu cocina. Como tienda de cocinas en Matar\u00f3 te mostrar\u00e1n todas las posibilidades que te ofrece el cat\u00e1logo de OB Cocinas, con todas sus actualizaciones. Desde materiales y acabados, pasando por la gran variedad de colores, tiradores, sistemas de apertura, cajones y gavetas y hasta las diversas opciones de iluminaci\u00f3n que tenemos disponibles. No importa cual sea tu estilo, ellos lo captar\u00e1n y te guiar\u00e1n durante todo el proceso procurando tu plena satisfacci\u00f3n. Como ya sabes son especialistas en muebles de cocina en Matar\u00f3 pero tambi\u00e9n cuentan con el equipo y la experiencia m\u00e1s que de sobra para llevar a cabo la reforma integral. Por todo esto y mucho m\u00e1s, XFreixer es tu tienda de cocinas en Matar\u00f3. \u00bfA qu\u00e9 esperas para conocerlos?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tienda de cocinas en Matar\u00f3 Si est\u00e1s buscando muebles de cocina en Matar\u00f3 no puedes dejar de visitar XFreixer. Dise\u00f1o de alto nivel y todas las colecciones de OB Cocinas a tu disposici\u00f3n. Adem\u00e1s de ser unos de los mayores expertos en cocinas en Madrid con una amplia experiencia en dise\u00f1o y mobiliario, en XFreixer [&hellip;]<\/p>\n","protected":false},"featured_media":7088,"template":"","ciudad":[766],"provincia":[722],"pais":[416],"class_list":["post-10101","tienda","type-tienda","status-publish","has-post-thumbnail","hentry","ciudad-mataro","provincia-barcelona","pais-espana"],"_links":{"self":[{"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/tienda\/10101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/tienda"}],"about":[{"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/types\/tienda"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/media\/7088"}],"wp:attachment":[{"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/media?parent=10101"}],"wp:term":[{"taxonomy":"ciudad","embeddable":true,"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/ciudad?post=10101"},{"taxonomy":"provincia","embeddable":true,"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/provincia?post=10101"},{"taxonomy":"pais","embeddable":true,"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/pais?post=10101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}