{"id":10083,"date":"2025-11-14T15:37:20","date_gmt":"2025-11-14T14:37:20","guid":{"rendered":"https:\/\/dev.obcocinas.com\/tienda\/i9-cozinhas-porto-matosinhos\/"},"modified":"2025-11-30T22:07:55","modified_gmt":"2025-11-30T21:07:55","slug":"i9-cozinhas-porto-matosinhos","status":"publish","type":"tienda","link":"https:\/\/obcocinas.es\/fr\/magasin\/i9-cozinhas-porto-matosinhos\/","title":{"rendered":"I9 Cozinhas Porto"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Torne o seu sonho realidade<\/h3>\n\n\n\n<p>Como \u00e9 a sua cozinha de sonho? Branca e minimalista? Aconchegante e tradicional? Ou prefere seguir as \u00faltimas tend\u00eancias a n\u00edvel de cores? Seja qual for o seu sonho, a i9 Cozinhas pode torn\u00e1-lo realidade. O revendedor OB Cocinas em Le\u00e7a da Palmeira (Matosinhos, distrito do Porto) tem uma vis\u00e3o clara do seu trabalho: cada projeto que concebe tem uma parte do cliente e uma parte de si pr\u00f3prio. Por outras palavras, envolve-se em cada nova cozinha como se fosse a sua pr\u00f3pria cozinha. Gostaria de ficar a conhecer esta equipa?<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">O seu mobili\u00e1rio OB Cocinas na i9 Cozinhas<\/h3>\n\n\n\n<p>Se quiser ver uma exposi\u00e7\u00e3o dos nossos m\u00f3veis de cozinha, bem como uma grande montra com os diferentes acabamentos dispon\u00edveis, tem de visitar a loja i9 Cozinhas. Pode encontr\u00e1-la na Avenida Doutor Fernando Aroso 668, em Le\u00e7a da Palmeira. O seu hor\u00e1rio de funcionamento \u00e9 de segunda a sexta-feira, das 9h00 \u00e0s 13h00 e das 15h00 \u00e0s 19h00. N\u00e3o deixe de os visitar!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">A sua cozinha com a OB Cocinas<\/h3>\n\n\n\n<p>Seja qual for a ideia para a sua cozinha, com o know-how da i9 Cozinhas e a grande variedade de designs e acess\u00f3rios dos nossos m\u00f3veis, certamente conseguir\u00e1 realiz\u00e1-la. A equipa de decoradores do nosso distribuidor vai ouvir as suas ideias e orient\u00e1-lo na planifica\u00e7\u00e3o da distribui\u00e7\u00e3o de todos os elementos da cozinha para otimizar o espa\u00e7o e adapt\u00e1-lo \u00e0s suas necessidades di\u00e1rias. Da mesma forma, v\u00e3o tamb\u00e9m aconselh\u00e1-lo sobre as diferentes op\u00e7\u00f5es est\u00e9ticas em fun\u00e7\u00e3o dos seus gostos, mostrando-lhe combina\u00e7\u00f5es de materiais que talvez nem sequer tenha imaginado mas&#8230; pelas quais se vai apaixonar! Uma vez terminada a fase de projeto, a i9 Cozinhas encarrega-se de todo o processo de remodela\u00e7\u00e3o e instala\u00e7\u00e3o da sua nova cozinha, para que s\u00f3 tenha de se preocupar em desfrutar dela.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Torne o seu sonho realidade Como \u00e9 a sua cozinha de sonho? Branca e minimalista? Aconchegante e tradicional? Ou prefere seguir as \u00faltimas tend\u00eancias a n\u00edvel de cores? Seja qual for o seu sonho, a i9 Cozinhas pode torn\u00e1-lo realidade. O revendedor OB Cocinas em Le\u00e7a da Palmeira (Matosinhos, distrito do Porto) tem uma vis\u00e3o [&hellip;]<\/p>\n","protected":false},"featured_media":7070,"template":"","ciudad":[748],"provincia":[467],"pais":[451],"class_list":["post-10083","tienda","type-tienda","status-publish","has-post-thumbnail","hentry","ciudad-matosinhos","provincia-oporto","pais-portugal"],"_links":{"self":[{"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/tienda\/10083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/tienda"}],"about":[{"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/types\/tienda"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/media\/7070"}],"wp:attachment":[{"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/media?parent=10083"}],"wp:term":[{"taxonomy":"ciudad","embeddable":true,"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/ciudad?post=10083"},{"taxonomy":"provincia","embeddable":true,"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/provincia?post=10083"},{"taxonomy":"pais","embeddable":true,"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/pais?post=10083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}