{"id":11255,"date":"2022-03-25T00:00:00","date_gmt":"2022-03-24T23:00:00","guid":{"rendered":"https:\/\/dev.obcocinas.com\/noticias\/nuestras-cocinas-fenix\/"},"modified":"2025-12-02T16:56:50","modified_gmt":"2025-12-02T15:56:50","slug":"nos-cuisines-fnix","status":"publish","type":"post","link":"https:\/\/obcocinas.es\/fr\/blog\/nos-cuisines-fnix\/","title":{"rendered":"Nos cuisines : F\u00e9nix"},"content":{"rendered":"<div><p>Moderne, multifonctionnelle, lumineuse, Voil\u00e0 notre cuisine F\u00e9nix. Une cuisine pens\u00e9e et con\u00e7ue pour tous types de maisons et de styles de vie, avec un design tr\u00e8s tendance.<\/p><p>La gamme F\u00e9nix ne perd jamais de vue le concept PR-19. Ce concept innovant, d\u00e9velopp\u00e9 par OB Cocinas, est l\u2019alliance parfaite entre fonctionnalit\u00e9, design et qualit\u00e9. Le r\u00e9sultat\u00a0: des cuisines en parfaite harmonie avec les besoins de chaque foyer.\u00a0<\/p><h2>Faites entrer la lumi\u00e8re<\/h2><p>Le blanc a toujours \u00e9t\u00e9 un classique dans les cuisines. En effet, cette couleur apporte beaucoup plus que ce que l\u2019on pourrait croire \u00e0 cette pi\u00e8ce. Bien s\u00fbr, le blanc est le principal responsable de sa luminosit\u00e9. Et, dans notre cuisine F\u00e9nix, ce sentiment de calme s\u2019\u00e9l\u00e8ve \u00e0 un niveau sup\u00e9rieur.<\/p><p>Ses lignes sobres et le syst\u00e8me d\u2019ouverture \u00e0 gorge donnent d\u2019autant plus d\u2019harmonie et une sensation d\u2019espace \u00e0 l\u2019ensemble. Non seulement les poign\u00e9es \u00e0 gorge sont esth\u00e9tiquement simples, mais elles facilitent aussi l\u2019ouverture des tiroirs et des placards dans toute la cuisine, aussi bien horizontalement que verticalement. La fonctionnalit\u00e9 et l\u2019esth\u00e9tique deviennent alors ins\u00e9parables. Surtout que vous pouvez choisir la couleur de la gorge. Cette fois, nous nous sommes laiss\u00e9 emporter par la tendance et nous avons choisi le dor\u00e9.<\/p><p>Et parmi les innombrables avantages de ce design, on peut souligner qu\u2019il peut aller \u00e0 merveille avec n\u2019importe quel style de d\u00e9coration. Quels que soient vos go\u00fbts, le design de votre maison ou votre style de vie, la cuisine F\u00e9nix vous ira comme un gant.<\/p><\/div><div><figure class=\"wp-block-image size-full ob-post-image\"><img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1125\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\" src=\"https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/luz.-pim2-2000_q.jpg\" alt=\"Cocina moderna con isla blanca, vitrinas de madera y amplios ventanales con luz natural.\" class=\"wp-image-3692\" srcset=\"https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/luz.-pim2-2000_q-jpg.avif 2000w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/luz.-pim2-2000_q-1024x576-jpg.avif 1024w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/luz.-pim2-2000_q-1536x864-jpg.avif 1536w\" \/><\/figure><\/div><div><h2>Pensez \u00e0 F\u00e9nix<\/h2><p>Les mat\u00e9riaux F\u00e9nix sont \u00e0 la pointe de l\u2019innovation en mati\u00e8re de design d\u2019int\u00e9rieur, avec une surface extr\u00eamement mate. De plus, gr\u00e2ce \u00e0 sa couche externe unique non poreuse, la surface reste propre plus longtemps et plus facilement. Non seulement elle est anti-traces de doigts, elle est aussi tr\u00e8s r\u00e9sistante aux rayures et aux produits chimiques.<\/p><h2>La beaut\u00e9 est \u00e0 l\u2019int\u00e9rieur<\/h2><p>La cuisine F\u00e9nix, comme toutes les gammes d\u2019OB Cocinas, cache en son int\u00e9rieur ses d\u00e9tails les plus pr\u00e9cieux. Commen\u00e7ons par le support d\u2019\u00e9tag\u00e8re embouti anti-renversement Kintai Il apporte une grande stabilit\u00e9 et r\u00e9sistance aux \u00e9tag\u00e8res et autres modules de d\u00e9coration. De plus, la structure des meubles et des \u00e9tag\u00e8res de la cuisine F\u00e9nix est tr\u00e8s solide car ceux-ci sont compos\u00e9s de panneaux de bois lamell\u00e9 de 19 mm d\u2019\u00e9paisseur.<\/p><p>Le but est de se simplifier la vie et c&rsquo;est pour cela nous avons des solutions telles que le syst\u00e8me Lemans, un \u00e9l\u00e9gant meuble d\u2019angle qui tire profit au maximum de l\u2019espace. Un meuble utile et pratique pour le rangement de vos ustensiles de cuisine comme les po\u00eales ou les casseroles qui, de surcro\u00eet, vous permet de maintenir de l\u2019ordre et d\u2019avoir tout ce qu\u2019il vous faut \u00e0 port\u00e9e de main.<\/p><\/div><div><figure class=\"wp-block-image size-full ob-post-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1536\" height=\"2048\" sizes=\"auto, (max-width: 1536px) 100vw, 1536px\" src=\"https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/lemans.-pim2-2000_q.jpg\" alt=\"Mueble de cocina con sistema extra\u00edble para organizar ollas y sartenes en esquina\" class=\"wp-image-3693\" srcset=\"https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/lemans.-pim2-2000_q-jpg.avif 1536w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/lemans.-pim2-2000_q-225x300.jpg 225w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/lemans.-pim2-2000_q-1152x1536-jpg.avif 1152w\" \/><\/figure><\/div><div><p>Et n\u2019oublions pas la charni\u00e8re Silentia+. Elle garantit une fermeture parfaite et en douceur de la porte en toutes circonstances, quelle que soit la disposition et l\u2019utilisation, gr\u00e2ce \u00e0 sa technologie de fermeture amortie avec deux amortisseurs d\u2019huile de silicone. En outre, elle est \u00e9quip\u00e9e d\u2019un s\u00e9lecteur innovant pour retarder l\u2019action d\u2019amortissement.\u00a0<\/p><p>L\u2019espace pour le recyclage est indispensable dans une cuisine. Chez OB Cocinas nous en sommes conscients et c\u2019est pour cette raison que nous avons con\u00e7u Pull boy, un meuble plaisant et tr\u00e8s, tr\u00e8s utile pour faire le tri des d\u00e9chets et garder la cuisine propre.<\/p><\/div><div><figure class=\"wp-block-image size-full ob-post-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1536\" height=\"2048\" sizes=\"auto, (max-width: 1536px) 100vw, 1536px\" src=\"https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/pullboy.-pim2-2000_q.jpg\" alt=\"Caj\u00f3n de cocina con cubetas organizadoras y contenedores de reciclaje integrados.\" class=\"wp-image-3694\" srcset=\"https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/pullboy.-pim2-2000_q-jpg.avif 1536w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/pullboy.-pim2-2000_q-225x300.jpg 225w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/pullboy.-pim2-2000_q-1152x1536-jpg.avif 1152w\" \/><\/figure><\/div><div><h2>Une cuisine \u00e0 vivre<\/h2><\/div><div><figure class=\"wp-block-image size-full ob-post-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1365\" height=\"2048\" sizes=\"auto, (max-width: 1365px) 100vw, 1365px\" src=\"https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/barrasnack.-pim2-2000_q.jpg\" alt=\"Isla de cocina con encimera de madera, taburetes dorados y mobiliario en tonos claros.\" class=\"wp-image-3695\" srcset=\"https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/barrasnack.-pim2-2000_q-jpg.avif 1365w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/barrasnack.-pim2-2000_q-200x300-jpg.avif 200w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/barrasnack.-pim2-2000_q-683x1024-jpg.avif 683w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/barrasnack.-pim2-2000_q-1024x1536-jpg.avif 1024w\" \/><\/figure><\/div><div><p>Le design et la fonctionnalit\u00e9 que recherche OB Cocinas ont un seul et unique objectif\u00a0: cr\u00e9er des cuisines \u00e0 vivre et o\u00f9 vivre. C\u2019est pourquoi, en plus de profiter de nos \u00e9quipements et de nos int\u00e9rieurs, vous pouvez compl\u00e9ter votre cuisine F\u00e9nix avec d\u2019autres \u00e9l\u00e9ments comme le bar petit-d\u00e9jeuner ou la vitrine Bold, qui apporteront une touche de chic \u00e0 votre cuisine, surtout en association avec la lumi\u00e8re int\u00e9rieure et ext\u00e9rieure, et qui vous feront gagner de l&rsquo;espace de rangement.<\/p><\/div><div><figure class=\"wp-block-image size-full ob-post-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1536\" height=\"2048\" sizes=\"auto, (max-width: 1536px) 100vw, 1536px\" src=\"https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/vitrina.-pim2-2000_q.jpg\" alt=\"Vitrinas de cocina con interior de madera, iluminaci\u00f3n c\u00e1lida y vajilla decorativa.\" class=\"wp-image-3696\" srcset=\"https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/vitrina.-pim2-2000_q-jpg.avif 1536w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/vitrina.-pim2-2000_q-225x300-jpg.avif 225w, https:\/\/obcocinas.es\/wp-content\/uploads\/2025\/11\/vitrina.-pim2-2000_q-1152x1536-jpg.avif 1152w\" \/><\/figure><\/div><div><p>Cliquez <strong>ici <\/strong>pour d\u00e9couvrir tous les d\u00e9tails de notre cuisine F\u00e9nix<\/p><\/div>","protected":false},"excerpt":{"rendered":"<p>Moderne, multifonctionnelle, lumineuse, Voil\u00e0 notre cuisine F\u00e9nix. Une cuisine pens\u00e9e et con\u00e7ue pour tous types de maisons et de styles de vie, avec un design tr\u00e8s tendance. La gamme F\u00e9nix ne perd jamais de vue le concept PR-19. Ce concept innovant, d\u00e9velopp\u00e9 par OB Cocinas, est l\u2019alliance parfaite entre fonctionnalit\u00e9, design et qualit\u00e9. Le r\u00e9sultat\u00a0: [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9768,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1070],"tags":[],"class_list":["post-11255","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nos-cuisines"],"_links":{"self":[{"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/posts\/11255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/comments?post=11255"}],"version-history":[{"count":1,"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/posts\/11255\/revisions"}],"predecessor-version":[{"id":11588,"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/posts\/11255\/revisions\/11588"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/media\/9768"}],"wp:attachment":[{"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/media?parent=11255"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/categories?post=11255"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/tags?post=11255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}