{"id":10766,"date":"2025-09-25T00:00:00","date_gmt":"2025-09-24T22:00:00","guid":{"rendered":"https:\/\/dev.obcocinas.com\/noticias\/nuevo-catalogo-ob-cocinas-encuentra-tu-estilo-crea-tu-cocina\/"},"modified":"2025-12-02T16:13:50","modified_gmt":"2025-12-02T15:13:50","slug":"nouveau-catalogue-ob-cocinas-trouvez-votre-style","status":"publish","type":"post","link":"https:\/\/obcocinas.es\/fr\/blog\/nouveau-catalogue-ob-cocinas-trouvez-votre-style\/","title":{"rendered":"Nouveau catalogue OB Cocinas: trouvez votre style, cr\u00e9ez votre cuisine"},"content":{"rendered":"<div>\n<p>C&rsquo;est officiel. Nous avons enfin entre les mains ce que nous pr\u00e9parons depuis longtemps avec beaucoup d&rsquo;enthousiasme : notre nouveau catalogue. Plus de 80 pages d&rsquo;inspiration pure qui arrivent d\u00e9j\u00e0 dans les ateliers et les salles d&rsquo;exposition de tous nos distributeurs, pr\u00eates \u00e0 vous enthousiasmer et \u00e0 vous aider \u00e0 concevoir la cuisine que vous imaginez.<\/p>\n<p>Nous avons con\u00e7u ce catalogue non seulement comme une collection de mod\u00e8les et de finitions, mais aussi comme une invitation \u00e0 trouver votre propre style.<\/p>\n<p>Vous y trouverez diff\u00e9rentes propositions de design dans lesquelles nous utilisons certains des mod\u00e8les que nous connaissons d\u00e9j\u00e0, comme Liverpool ou Montreal, mais aussi certaines de nos nouveaut\u00e9s, comme les mod\u00e8les Casella, Moa ou Parona.<\/p>\n<p>Conform\u00e9ment aux derni\u00e8res tendances en mati\u00e8re de d\u00e9coration int\u00e9rieure, ces propositions sont domin\u00e9es par des couleurs neutres, des textures et des finitions qui nous rappellent la nature, comme la pierre, le bois ou les tons verts.<\/p>\n<p>Chacune a son propre langage, sa propre esth\u00e9tique, sa propre essence. Et il y en a forc\u00e9ment une dans laquelle vous vous reconna\u00eetrez.<\/p>\n<p>Dans notre nouveau catalogue, vous pourrez \u00e9galement d\u00e9couvrir quelques-unes de nos plus de 50 finitions unicolores, comme l&rsquo;os, le gris perle, le moka, l&rsquo;argile, la terre cuite et le bleu indigo. Des teintes qui transmettent des sensations et vous permettent de personnaliser votre cuisine jusque dans les moindres d\u00e9tails.<\/p>\n<p>Nous vous pr\u00e9sentons \u00e9galement certaines de nos finitions en bois qui triomphent d\u00e9j\u00e0 dans les projets de nos distributeurs, ainsi qu&rsquo;une s\u00e9lection de finitions design qui allient innovation et esth\u00e9tique.<\/p>\n<p>Notre nouveau catalogue comprend de nombreux autres d\u00e9tails que vous pouvez choisir et personnaliser, tels que les structures int\u00e9rieures, les modules de rangement et les accessoires qui feront de votre cuisine un espace efficace.<\/p>\n<p>Mais il vaut mieux le voir de ses propres yeux, n&rsquo;est-ce pas ?<\/p>\n<p>Vous pouvez d&rsquo;ores et d\u00e9j\u00e0 consulter le nouveau catalogue dans le magasin de votre revendeur le plus proche et commencer \u00e0 imaginer votre cuisine id\u00e9ale. <\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>C&rsquo;est officiel. Nous avons enfin entre les mains ce que nous pr\u00e9parons depuis longtemps avec beaucoup d&rsquo;enthousiasme : notre nouveau catalogue. Plus de 80 pages d&rsquo;inspiration pure qui arrivent d\u00e9j\u00e0 dans les ateliers et les salles d&rsquo;exposition de tous nos distributeurs, pr\u00eates \u00e0 vous enthousiasmer et \u00e0 vous aider \u00e0 concevoir la cuisine que vous [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9789,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1073,1070],"tags":[],"class_list":["post-10766","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entreprise","category-nos-cuisines"],"_links":{"self":[{"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/posts\/10766","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/comments?post=10766"}],"version-history":[{"count":1,"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/posts\/10766\/revisions"}],"predecessor-version":[{"id":11593,"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/posts\/10766\/revisions\/11593"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/media\/9789"}],"wp:attachment":[{"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/media?parent=10766"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/categories?post=10766"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/obcocinas.es\/fr\/wp-json\/wp\/v2\/tags?post=10766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}