{"id":10433,"date":"2025-11-12T21:55:52","date_gmt":"2025-11-12T20:55:52","guid":{"rendered":"https:\/\/dev.obcocinas.com\/tienda\/cdc-cocinas-guadalajara\/"},"modified":"2025-11-30T22:10:54","modified_gmt":"2025-11-30T21:10:54","slug":"cdc-cocinas-guadalajara","status":"publish","type":"tienda","link":"https:\/\/obcocinas.es\/en\/store\/cdc-cocinas-guadalajara\/","title":{"rendered":"CDC Cocinas"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Imagina tu nueva cocina con CDC Cocinas<\/h3>\n\n\n\n<p>\u00bfBuscas un distribuidor de OB Cocinas en Guadalajara para la reforma de tu cocina? Sigue leyendo porque vamos a hablarte de una empresa que te va a interesar: CDC Cocinas. La variedad de estilos y tipos de cocina que vas a encontrar en CDC Cocinas es impresionante. Si quieres una cocina minimalista en tonos neutros, o algo m\u00e1s r\u00fastico con acabados en materiales nobles o, tal vez, una cocina que mezcle tonos en tendencia y accesorios modernos, aqu\u00ed la vas a encontrar. Y si a\u00fan no te has decidido por qu\u00e9 estilo quieres darle a tu nueva cocina, \u00a1casi mejor! En CDC Cocinas te ayudar\u00e1n a encontrarlo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Tu tienda de cocinas en Guadalajara<\/h3>\n\n\n\n<p>En su tienda, CDC Cocinas cuenta con un gran espacio dedicado a la exposici\u00f3n de muchos de modelos de nuestro cat\u00e1logo. Podr\u00e1s comprobar in situ qu\u00e9 acabados, materiales y colores combinan mejor, qu\u00e9 tiradores te resultan m\u00e1s c\u00f3modos y las ventajas organizativas y de almacenamiento de nuestros accesorios interiores. El equipo de CDC Cocinas te espera en la calle Virgen del Amparo, 38-2; en Guadalajara y a menos de una hora de Madrid por la A-2. Y para pon\u00e9rtelo a\u00fan m\u00e1s f\u00e1cil, tienen un amplio horario. Abren de lunes a viernes 10 a 13:30 y de 16 a 20 horas, y tambi\u00e9n los s\u00e1bados de 10:30 a 13:30 horas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Haz M\u00e1s Vida en la Cocina con OB Cocinas<\/h3>\n\n\n\n<p>Adem\u00e1s de tener una \u00e1rea de exposici\u00f3n en la que conocer algunos de los modelos de OB Cocinas y muestras de acabados, colores y materiales de nuestro cat\u00e1logo, CDC Cocinas ofrece una amplia selecci\u00f3n de electrodom\u00e9sticos de reconocidas marcas, as\u00ed como una variada gama de accesorios de cocina. Desde utensilios de cocina hasta sistemas de almacenamiento y organizaci\u00f3n, la tienda tiene todo lo necesario para crear una cocina funcional y bien equipada. Tambi\u00e9n podr\u00e1s escoger entre su gran variedad de encimeras, revestimientos e incluso mesas y sillas para equipar tu cocina al completo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Imagina tu nueva cocina con CDC Cocinas \u00bfBuscas un distribuidor de OB Cocinas en Guadalajara para la reforma de tu cocina? Sigue leyendo porque vamos a hablarte de una empresa que te va a interesar: CDC Cocinas. La variedad de estilos y tipos de cocina que vas a encontrar en CDC Cocinas es impresionante. Si [&hellip;]<\/p>\n","protected":false},"featured_media":7080,"template":"","ciudad":[604],"provincia":[1032],"pais":[],"class_list":["post-10433","tienda","type-tienda","status-publish","has-post-thumbnail","hentry","ciudad-guadalajara","provincia-guadalajara"],"_links":{"self":[{"href":"https:\/\/obcocinas.es\/en\/wp-json\/wp\/v2\/tienda\/10433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/obcocinas.es\/en\/wp-json\/wp\/v2\/tienda"}],"about":[{"href":"https:\/\/obcocinas.es\/en\/wp-json\/wp\/v2\/types\/tienda"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/obcocinas.es\/en\/wp-json\/wp\/v2\/media\/7080"}],"wp:attachment":[{"href":"https:\/\/obcocinas.es\/en\/wp-json\/wp\/v2\/media?parent=10433"}],"wp:term":[{"taxonomy":"ciudad","embeddable":true,"href":"https:\/\/obcocinas.es\/en\/wp-json\/wp\/v2\/ciudad?post=10433"},{"taxonomy":"provincia","embeddable":true,"href":"https:\/\/obcocinas.es\/en\/wp-json\/wp\/v2\/provincia?post=10433"},{"taxonomy":"pais","embeddable":true,"href":"https:\/\/obcocinas.es\/en\/wp-json\/wp\/v2\/pais?post=10433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}