{"id":10424,"date":"2025-11-12T22:04:47","date_gmt":"2025-11-12T21:04:47","guid":{"rendered":"https:\/\/dev.obcocinas.com\/tienda\/clp-design-fuentealbilla\/"},"modified":"2025-11-30T22:10:50","modified_gmt":"2025-11-30T21:10:50","slug":"clp-design-fuentealbilla","status":"publish","type":"tienda","link":"https:\/\/obcocinas.es\/en\/store\/clp-design-fuentealbilla\/","title":{"rendered":"Clp Design"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Cocinas en Albacete<\/h3>\n\n\n\n<p>CPL Design es la tienda de cocinas en Albacete que andabas buscando. Son grandes especialistas en dise\u00f1o de cocinas e interiorismo y desarrollan maravillosos proyectos de cocinas modernas, funcionales y siempre de la mejor calidad. Como queremos que cuentes con los muebles de OB Cocinas y confiamos plenamente en nuestro distribuidor de cocinas en Albacete, te recomendamos que prestes atenci\u00f3n a todo lo que tenemos que contarte sobre CPL Design.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Tienda distribuidora de OB Cocinas en Albacete<\/h3>\n\n\n\n<p>En el coraz\u00f3n de esta preciosa ciudad encontrar\u00e1s CPL Design, tu tienda de cocinas en Albacete. Situado en pleno centro hist\u00f3rico, en la calle Carnicer\u00edas 6, y rodeado de los m\u00e1s importantes monumentos, encontrar\u00e1s el establecimiento de CPL Design. Adem\u00e1s de las m\u00e1s actuales cocinas en Albacete en su tienda te espera su equipo de interioristas especializados en cocinas, que te atender\u00e1n de maravilla de lunes a viernes de 17 a 20 horas. [&#8230;]<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Muebles de cocina de dise\u00f1o y a medida<\/h3>\n\n\n\n<p>\u00bfQu\u00e9 buscas cuando estudias las tiendas de cocinas en Albacete? Seguro que lo primero en que te fijas son los modelos y dise\u00f1os. En CPL Design cuentan con modelos de OB Cocinas expuestos en su local, pero tambi\u00e9n con muestras de todo nuestro cat\u00e1logo actualizado. Materiales, acabados, colores, perfiles y tiradores\u2026 Todo un mundo de posibilidades te espera en CPL Design. Es m\u00e1s, all\u00ed mismo podr\u00e1s elegir tambi\u00e9n los grifos, la encimera e incluso suelos y revestimientos. Todo lo que necesitas para hacer realidad tu cocina lo vas a encontrar all\u00ed. Pero sigamos con los requisitos que debe cumplir tu tienda de cocinas en Albacete. Otro de los imprescindibles es la experiencia. En este sentido tambi\u00e9n puedes respirar con calma porque en CPL Design llevan muchos a\u00f1os dise\u00f1ando, reformando y haciendo realidad cientos de proyectos de cocina. Adem\u00e1s, esta experiencia les lleva tambi\u00e9n a ser grandes asesores. En todo momento te aconsejar\u00e1n sobre qu\u00e9 decisi\u00f3n debes tomar, en caso de que se planteen dudas. Pero si tienes bien claro todos y cada uno de los detalles de tu nueva cocina y lo \u00fanico que necesitas es que alguien la ponga en pie, no dudes de que tambi\u00e9n son la mejor opci\u00f3n. Escuchar\u00e1n todas tus ideas, sugerencias y, sobre todo, tus necesidades. Lo meter\u00e1n todo en una coctelera y, \u00a1vual\u00e1! \u00bfSe te ocurre alguna condici\u00f3n m\u00e1s? \u00a1Por supuesto! El compromiso. En CPL Design no dejan nada al azar. Ni el presupuesto, ni la entrega, ni ning\u00fan otro detalle. El minucioso seguimiento que hacen de sus cocinas en Albacete te dar\u00e1n toda la tranquilidad y confianza que necesitas. Te mantendr\u00e1n informado en todo momento de los avances y las diferentes fases del proyecto, para que no te pierdas nada y puedas decidir lo que sea necesario sobre la marcha. \u00bfQu\u00e9 m\u00e1s? \u00a1Ah, s\u00ed! Nunca van a perder de vista su m\u00e1ximo objetivo: que puedas hacer M\u00e1s Vida en la Cocina. \u00bfA qu\u00e9 esperas para ir a conocerlos?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cocinas en Albacete CPL Design es la tienda de cocinas en Albacete que andabas buscando. Son grandes especialistas en dise\u00f1o de cocinas e interiorismo y desarrollan maravillosos proyectos de cocinas modernas, funcionales y siempre de la mejor calidad. Como queremos que cuentes con los muebles de OB Cocinas y confiamos plenamente en nuestro distribuidor de [&hellip;]<\/p>\n","protected":false},"featured_media":7055,"template":"","ciudad":[1023],"provincia":[413],"pais":[],"class_list":["post-10424","tienda","type-tienda","status-publish","has-post-thumbnail","hentry","ciudad-fuentealbilla","provincia-albacete"],"_links":{"self":[{"href":"https:\/\/obcocinas.es\/en\/wp-json\/wp\/v2\/tienda\/10424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/obcocinas.es\/en\/wp-json\/wp\/v2\/tienda"}],"about":[{"href":"https:\/\/obcocinas.es\/en\/wp-json\/wp\/v2\/types\/tienda"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/obcocinas.es\/en\/wp-json\/wp\/v2\/media\/7055"}],"wp:attachment":[{"href":"https:\/\/obcocinas.es\/en\/wp-json\/wp\/v2\/media?parent=10424"}],"wp:term":[{"taxonomy":"ciudad","embeddable":true,"href":"https:\/\/obcocinas.es\/en\/wp-json\/wp\/v2\/ciudad?post=10424"},{"taxonomy":"provincia","embeddable":true,"href":"https:\/\/obcocinas.es\/en\/wp-json\/wp\/v2\/provincia?post=10424"},{"taxonomy":"pais","embeddable":true,"href":"https:\/\/obcocinas.es\/en\/wp-json\/wp\/v2\/pais?post=10424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}