{"id":10412,"date":"2025-11-12T22:20:15","date_gmt":"2025-11-12T21:20:15","guid":{"rendered":"https:\/\/dev.obcocinas.com\/tienda\/cocinas-marbella-marbella\/"},"modified":"2025-11-30T22:10:43","modified_gmt":"2025-11-30T21:10:43","slug":"cocinas-marbella-marbella","status":"publish","type":"tienda","link":"https:\/\/obcocinas.es\/en\/store\/cocinas-marbella-marbella\/","title":{"rendered":"Cocinas Marbella"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Tu cocina hecha a tu medida<\/h3>\n\n\n\n<p>Ya sea una cocina moderna y minimalista, o una cocina cl\u00e1sica de est\u00e9tica m\u00e1s r\u00fastica, en el cat\u00e1logo de OB Cocinas vas a encontrar el estilo que quieras definir para tu nueva cocina y en Cocinas Marbella van a hacerlo realidad.<br>\u00bfTienes poco espacio? \u00bfO quieres una gran cocina con isla que se una al sal\u00f3n? La configuraci\u00f3n de tu cocina no va a ser un problema. En esta tienda de cocinas no solo venden mobiliario, tambi\u00e9n realizan los proyectos de manera integral, desde el plano hasta la entrega \u201cllave en mano\u201d. Disfruta de tu nueva cocina con Cocinas Marbella y empieza a hacer M\u00e1s Vida en la Cocina.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tu cocina hecha a tu medida Ya sea una cocina moderna y minimalista, o una cocina cl\u00e1sica de est\u00e9tica m\u00e1s r\u00fastica, en el cat\u00e1logo de OB Cocinas vas a encontrar el estilo que quieras definir para tu nueva cocina y en Cocinas Marbella van a hacerlo realidad.\u00bfTienes poco espacio? \u00bfO quieres una gran cocina con [&hellip;]<\/p>\n","protected":false},"featured_media":7101,"template":"","ciudad":[1011],"provincia":[703],"pais":[],"class_list":["post-10412","tienda","type-tienda","status-publish","has-post-thumbnail","hentry","ciudad-marbella","provincia-malaga"],"_links":{"self":[{"href":"https:\/\/obcocinas.es\/en\/wp-json\/wp\/v2\/tienda\/10412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/obcocinas.es\/en\/wp-json\/wp\/v2\/tienda"}],"about":[{"href":"https:\/\/obcocinas.es\/en\/wp-json\/wp\/v2\/types\/tienda"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/obcocinas.es\/en\/wp-json\/wp\/v2\/media\/7101"}],"wp:attachment":[{"href":"https:\/\/obcocinas.es\/en\/wp-json\/wp\/v2\/media?parent=10412"}],"wp:term":[{"taxonomy":"ciudad","embeddable":true,"href":"https:\/\/obcocinas.es\/en\/wp-json\/wp\/v2\/ciudad?post=10412"},{"taxonomy":"provincia","embeddable":true,"href":"https:\/\/obcocinas.es\/en\/wp-json\/wp\/v2\/provincia?post=10412"},{"taxonomy":"pais","embeddable":true,"href":"https:\/\/obcocinas.es\/en\/wp-json\/wp\/v2\/pais?post=10412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}