{"id":10322,"date":"2025-11-13T15:37:54","date_gmt":"2025-11-13T14:37:54","guid":{"rendered":"https:\/\/dev.obcocinas.com\/tienda\/hermanos-rojas-ronda\/"},"modified":"2025-11-30T22:09:56","modified_gmt":"2025-11-30T21:09:56","slug":"hermanos-rojas-ronda","status":"publish","type":"tienda","link":"https:\/\/obcocinas.es\/en\/store\/hermanos-rojas-ronda\/","title":{"rendered":"Hermanos Rojas"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Cocinas en Ronda<\/h3>\n\n\n\n<p>Si buscas nuestros muebles para cocinas en Ronda, apunta este nombre: Muebles Hermanos Rojas. Como pod\u00e9is imaginar por su nombre, se trata de una empresa familiar. Concretamente, una familia que ha puesto todo su esfuerzo, ganas y pasi\u00f3n a este proyecto. Solo as\u00ed ha pasado de ser en 1979 una empresa dedicada al montaje de persianas, venta de cuadros y algunos mobiliarios; al referente que es hoy en mobiliario, decoraci\u00f3n y cocinas en Ronda y toda su Serran\u00eda. \u00bfQuieres saber m\u00e1s sobre ellos?<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Tienda de cocinas en Ronda<\/h3>\n\n\n\n<p>Nuestro distribuidor de muebles de cocina en Ronda cuenta con dos establecimientos en la localidad malague\u00f1a. Por un lado, una en pleno centro de la localidad, justo al lado de la estaci\u00f3n de autobuses y a tan solo 7 minutos a pie del ayuntamiento y de la hist\u00f3rica Plaza de Toros de la Real Maestranza de Caballer\u00eda de Ronda. Concretamente, podr\u00e1s encontrar nuestros muebles de cocina en Ronda en la calle Comandante Salvador Carrasco n\u00famero 17. All\u00ed te atender\u00e1 el equipo de Muebles Hermanos Rojas de lunes a viernes de 10 a 14 y de 16 a 20 h, as\u00ed como los s\u00e1bados en horario de ma\u00f1ana, de 10 a 13:30 h. Por otro lado, cuentan con una tienda de cocinas en Ronda dedicada exclusivamente a la exposici\u00f3n de muebles en la calle Tolox n\u00famero 2. En este establecimiento te atender\u00e1n de lunes a viernes de 9:30 a 14 h y de 16 a 20:30 h; y los s\u00e1bados de 9:30 a 14 h. Si vas a visitarlos en coche, en ambas zonas hay numerosos parkings, por lo que aparcar no es un problema. Si prefieres llegar a estas tiendas de muebles de cocina en Ronda desde otra localidad en transporte p\u00fablico; tienes la estaci\u00f3n de tren muy cerca justo a medio camino entre ambos establecimientos (a menos de 10 minutos a pie de cada una). [&#8230;]<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Comprar muebles de cocina de alta calidad y dise\u00f1o<\/h3>\n\n\n\n<p>Ya sabes d\u00f3nde acudir si quieres comprar muebles de cocina de alta calidad y dise\u00f1o; pero&#8230; \u00bfqu\u00e9 m\u00e1s vas a encontrar en estas tiendas de muebles de cocina en Ronda (M\u00e1laga)? Para empezar, un gran equipo humano. Al menos, esa es nuestra experiencia y tambi\u00e9n la de sus clientes durante todos estos a\u00f1os. En Muebles Hermanos Rojas te van a atender con cercan\u00eda, preocup\u00e1ndose por tus necesidades y expectativas; y teniendo muy en cuenta las particularidades de tu hogar a la hora de asesorarte en el dise\u00f1o de tu cocina en Ronda. Eso nos lleva a lo segundo que vas a encontrar en los establecimientos de nuestro distribuidor: profesionalidad y grandes soluciones. Por \u00faltimo, pero no por ello menos importante, en esta tienda de muebles de cocina en Ronda vas a encontrar compromiso con la calidad. Desde la elecci\u00f3n del mobiliario y dem\u00e1s materiales para tu cocina; hasta el montaje de los mismos en tu casa. \u00a1No lo dudes m\u00e1s y contacta con ellos ya!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cocinas en Ronda Si buscas nuestros muebles para cocinas en Ronda, apunta este nombre: Muebles Hermanos Rojas. Como pod\u00e9is imaginar por su nombre, se trata de una empresa familiar. Concretamente, una familia que ha puesto todo su esfuerzo, ganas y pasi\u00f3n a este proyecto. Solo as\u00ed ha pasado de ser en 1979 una empresa dedicada [&hellip;]<\/p>\n","protected":false},"featured_media":7101,"template":"","ciudad":[945],"provincia":[703],"pais":[412],"class_list":["post-10322","tienda","type-tienda","status-publish","has-post-thumbnail","hentry","ciudad-ronda","provincia-malaga","pais-spain"],"_links":{"self":[{"href":"https:\/\/obcocinas.es\/en\/wp-json\/wp\/v2\/tienda\/10322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/obcocinas.es\/en\/wp-json\/wp\/v2\/tienda"}],"about":[{"href":"https:\/\/obcocinas.es\/en\/wp-json\/wp\/v2\/types\/tienda"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/obcocinas.es\/en\/wp-json\/wp\/v2\/media\/7101"}],"wp:attachment":[{"href":"https:\/\/obcocinas.es\/en\/wp-json\/wp\/v2\/media?parent=10322"}],"wp:term":[{"taxonomy":"ciudad","embeddable":true,"href":"https:\/\/obcocinas.es\/en\/wp-json\/wp\/v2\/ciudad?post=10322"},{"taxonomy":"provincia","embeddable":true,"href":"https:\/\/obcocinas.es\/en\/wp-json\/wp\/v2\/provincia?post=10322"},{"taxonomy":"pais","embeddable":true,"href":"https:\/\/obcocinas.es\/en\/wp-json\/wp\/v2\/pais?post=10322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}