{"id":10187,"date":"2025-11-13T17:50:28","date_gmt":"2025-11-13T16:50:28","guid":{"rendered":"https:\/\/dev.obcocinas.com\/tienda\/rivas-sanchez-carpinteros-alcazar-de-san-juan\/"},"modified":"2025-11-30T22:08:48","modified_gmt":"2025-11-30T21:08:48","slug":"rivas-sanchez-carpinteros-alcazar-de-san-juan","status":"publish","type":"tienda","link":"https:\/\/obcocinas.es\/en\/store\/rivas-sanchez-carpinteros-alcazar-de-san-juan\/","title":{"rendered":"Rivas S\u00e1nchez Carpinteros"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Cocinas en Alc\u00e1zar de San Juan<\/h3>\n\n\n\n<p>Tu empresa especialista en cocinas en Alc\u00e1zar de San Juan no tiene nombre, sino dos apellidos: Rivas S\u00e1nchez Carpinteros. Con 35 a\u00f1os de experiencia en el sector, esta empresa familiar es un referente en cuanto a calidad y profesionalidad. Esta larga trayectoria les hace saber muy bien que elegir los muebles para tu cocina es un acontecimiento vital muy importante. Porque debe responder a tus necesidades, ser funcional y reflejar tu estilo y personalidad. Y, por supuesto, los materiales deben ser de gran calidad y durar muchos, muchos a\u00f1os. No lo dudes m\u00e1s. Rivas S\u00e1nchez Carpinteros son tus expertos en cocinas en Alc\u00e1zar de San Juan.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Tienda de muebles de cocina en Alc\u00e1zar de San Juan<\/h3>\n\n\n\n<p>Desde sus instalaciones en el Pol\u00edgono Industrial Arces, en la calle Cari\u00f1ena parcela B-19-20; difunden su filosof\u00eda de trabajo all\u00e1 donde van: el trabajo bien hecho. Con un elevado compromiso con la calidad y la satisfacci\u00f3n y la tranquilidad de todos sus clientes, puedes estar tranquilo al contar con ellos. Adem\u00e1s cuentan con una de las mayores ofertas de muebles de cocina en Alc\u00e1zar de San Juan. Si quieres visitarlos y conocer en directo a su gran equipo puedes hacerlo todos los d\u00edas, de lunes a viernes, de 7 a 15:30 horas. Te recomendamos que antes de pasarte por sus instalaciones pidas cita previa para que te dediquen el tiempo y la atenci\u00f3n que necesitas y te muestren su ofertas de cocina en Alc\u00e1zar de San Juan. [&#8230;]<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Conoce nuestra oferta de muebles para equipar tu cocina<\/h3>\n\n\n\n<p>Rivas S\u00e1nchez Carpinteros es distribuidor de OB Cocinas en Alc\u00e1zar de San Juan y, como tal, su equipo compuesto de experimentados carpinteros e interioristas son grandes conocedores de nuestro cat\u00e1logo. En cuanto los conozcas sabr\u00e1s que has tomado la decisi\u00f3n correcta al elegirlos. Se encargar\u00e1n de que conozcas a fondo y en directo todas las opciones disponibles en cuanto a materiales, acabados y colores, para llevar la idea que tienes de tu cocina a la realidad. Y si a\u00fan no tienes claro si decantarte por un estilo tradicional y r\u00fastico, o te gustar\u00eda algo m\u00e1s minimalista y neutro, sabr\u00e1n aconsejarte y despejar todas tus dudas. Como ya sabes, hay elementos muy importantes en cualquier cocina y que no deben descuidarse, como son los sistemas de apertura, los cajones y gavetas y todos los aspectos relacionados con la funcionalidad y el almacenaje. En el cat\u00e1logo de OB Cocinas disponemos de una gran variedad de soluciones que en Rivas S\u00e1nchez Carpinteros te explicar\u00e1n. \u00a1Pero no creas que todo esto queda en el aire! En Rivas S\u00e1nchez Carpinteros preparar\u00e1n una vista en 3D completa de tu nueva cocina antes de comenzar a ejecutar el proyecto. Y cuando por fin tengas tu cocina y sientas la gran satisfacci\u00f3n de haber contado con el mejor equipo de cocinas en Alc\u00e1zar de San Juan solo lamentar\u00e1s no haberlo hecho antes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cocinas en Alc\u00e1zar de San Juan Tu empresa especialista en cocinas en Alc\u00e1zar de San Juan no tiene nombre, sino dos apellidos: Rivas S\u00e1nchez Carpinteros. Con 35 a\u00f1os de experiencia en el sector, esta empresa familiar es un referente en cuanto a calidad y profesionalidad. Esta larga trayectoria les hace saber muy bien que elegir [&hellip;]<\/p>\n","protected":false},"featured_media":7086,"template":"","ciudad":[837],"provincia":[545],"pais":[412],"class_list":["post-10187","tienda","type-tienda","status-publish","has-post-thumbnail","hentry","ciudad-alcazar-de-san-juan","provincia-ciudad-real","pais-spain"],"_links":{"self":[{"href":"https:\/\/obcocinas.es\/en\/wp-json\/wp\/v2\/tienda\/10187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/obcocinas.es\/en\/wp-json\/wp\/v2\/tienda"}],"about":[{"href":"https:\/\/obcocinas.es\/en\/wp-json\/wp\/v2\/types\/tienda"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/obcocinas.es\/en\/wp-json\/wp\/v2\/media\/7086"}],"wp:attachment":[{"href":"https:\/\/obcocinas.es\/en\/wp-json\/wp\/v2\/media?parent=10187"}],"wp:term":[{"taxonomy":"ciudad","embeddable":true,"href":"https:\/\/obcocinas.es\/en\/wp-json\/wp\/v2\/ciudad?post=10187"},{"taxonomy":"provincia","embeddable":true,"href":"https:\/\/obcocinas.es\/en\/wp-json\/wp\/v2\/provincia?post=10187"},{"taxonomy":"pais","embeddable":true,"href":"https:\/\/obcocinas.es\/en\/wp-json\/wp\/v2\/pais?post=10187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}