{"id":10121,"date":"2025-11-14T15:00:01","date_gmt":"2025-11-14T14:00:01","guid":{"rendered":"https:\/\/dev.obcocinas.com\/tienda\/tuacasa-albacete-albacete\/"},"modified":"2025-11-30T22:08:15","modified_gmt":"2025-11-30T21:08:15","slug":"tuacasa-albacete-albacete","status":"publish","type":"tienda","link":"https:\/\/obcocinas.es\/en\/store\/tuacasa-albacete-albacete\/","title":{"rendered":"TUACASA ALBACETE"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Tienda de cocinas en Albacete<\/h3>\n\n\n\n<p>TuaCasa es distribuidor de OB Cocinas de cocinas en Albacete y como tal te ofrecen todo nuestro cat\u00e1logo de acabados y materiales. Su equipo de profesionales cuenta con una gran experiencia en el desarrollo de proyectos de cocinas en Melilla, \u00a1estar\u00e1s en las mejores manos! En su tienda no solo encontrar\u00e1s mobiliario de cocina, tambi\u00e9n muebles para otros espacios de la casa, \u00a1e incluso podr\u00e1s elegir los electrodom\u00e9sticos! Seguro que ya est\u00e1s buscando el momento para poder pasarte por su tienda en&nbsp;Campollano Avda.1-, esquina C.B.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Muebles de cocina de alta calidad y dise\u00f1o<\/h3>\n\n\n\n<p>Tanto si tienes claro tu estilo como si a\u00fan est\u00e1s buscando inspiraci\u00f3n, en TuaCasa tendr\u00e1s el asesoramiento que necesitas e innumerables opciones de cocinas en Albacete. Durante todo el proceso el personal de Tu casa te guiar\u00e1 en el proyecto de tu cocina, ayud\u00e1ndote a seleccionar el mobiliario adecuado y planificando el espacio centr\u00e1ndose en las necesidades de tu hogar. Como parte de su servicio integral, el montaje y la instalaci\u00f3n tambi\u00e9n corren de su cuenta. Puedes dar por seguro que tus nuevos muebles de cocina contar\u00e1n con la m\u00e1s alta calidad, con materiales innovadores y que, adem\u00e1s, est\u00e1n fabricados en Espa\u00f1a. All\u00ed podr\u00e1s consultar todo nuestro cat\u00e1logo de modelos, ver las opciones de los diferentes acabados y colores y sus combinaciones con accesorios para interiores, tiradores, grifer\u00edas, encimeras&#8230;&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tienda de cocinas en Albacete TuaCasa es distribuidor de OB Cocinas de cocinas en Albacete y como tal te ofrecen todo nuestro cat\u00e1logo de acabados y materiales. Su equipo de profesionales cuenta con una gran experiencia en el desarrollo de proyectos de cocinas en Melilla, \u00a1estar\u00e1s en las mejores manos! En su tienda no solo [&hellip;]<\/p>\n","protected":false},"featured_media":7086,"template":"","ciudad":[786],"provincia":[413],"pais":[412],"class_list":["post-10121","tienda","type-tienda","status-publish","has-post-thumbnail","hentry","ciudad-albacete","provincia-albacete","pais-spain"],"_links":{"self":[{"href":"https:\/\/obcocinas.es\/en\/wp-json\/wp\/v2\/tienda\/10121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/obcocinas.es\/en\/wp-json\/wp\/v2\/tienda"}],"about":[{"href":"https:\/\/obcocinas.es\/en\/wp-json\/wp\/v2\/types\/tienda"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/obcocinas.es\/en\/wp-json\/wp\/v2\/media\/7086"}],"wp:attachment":[{"href":"https:\/\/obcocinas.es\/en\/wp-json\/wp\/v2\/media?parent=10121"}],"wp:term":[{"taxonomy":"ciudad","embeddable":true,"href":"https:\/\/obcocinas.es\/en\/wp-json\/wp\/v2\/ciudad?post=10121"},{"taxonomy":"provincia","embeddable":true,"href":"https:\/\/obcocinas.es\/en\/wp-json\/wp\/v2\/provincia?post=10121"},{"taxonomy":"pais","embeddable":true,"href":"https:\/\/obcocinas.es\/en\/wp-json\/wp\/v2\/pais?post=10121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}